{"id":8698,"date":"2025-05-02T22:58:12","date_gmt":"2025-05-02T22:58:12","guid":{"rendered":"https:\/\/tableberg.com\/?p=8698"},"modified":"2025-05-04T10:00:53","modified_gmt":"2025-05-04T10:00:53","slug":"%d9%83%d9%8a%d9%81%d9%8a%d8%a9-%d8%a5%d9%86%d8%b4%d8%a7%d8%a1-%d8%aa%d8%a8%d8%af%d9%8a%d9%84-%d8%aa%d8%b3%d8%b9%d9%8a%d8%b1-%d8%b4%d9%87%d8%b1%d9%8a-%d8%b3%d9%86%d9%88%d9%8a-%d9%81%d9%8a-%d9%88%d9%88","status":"publish","type":"post","link":"https:\/\/tableberg.com\/ar\/how-to-create-a-monthly-yearly-pricing-toggle-in-wordpress\/","title":{"rendered":"\u0643\u064a\u0641\u064a\u0629 \u0625\u0646\u0634\u0627\u0621 \u062a\u0628\u062f\u064a\u0644 \u0627\u0644\u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u0634\u0647\u0631\u064a\/\u0627\u0644\u0633\u0646\u0648\u064a \u0641\u064a \u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633"},"content":{"rendered":"<p>\u064a\u0642\u0648\u0645 \u0627\u0644\u0645\u0634\u062a\u0631\u0648\u0646 \u0627\u0644\u064a\u0648\u0645 \u0628\u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0641\u064a \u062b\u0648\u0627\u0646\u064d \u0645\u0639\u062f\u0648\u062f\u0629: \u0627\u0644\u0628\u0639\u0636 \u064a\u0641\u062d\u0635\u0648\u0646 \u0627\u0644\u0623\u0633\u0639\u0627\u0631\u060c \u0648\u0627\u0644\u0628\u0639\u0636 \u0627\u0644\u0622\u062e\u0631 \u064a\u0642\u0627\u0631\u0646 \u0628\u064a\u0646 \u0627\u0644\u0645\u064a\u0632\u0627\u062a\u060c \u0648\u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646\u0647\u0645 \u064a\u0646\u0627\u0642\u0634\u0648\u0646 \u0627\u0644\u062e\u0637\u0637 \u0627\u0644\u0634\u0647\u0631\u064a\u0629 \u0645\u0642\u0627\u0628\u0644 \u0627\u0644\u062e\u0637\u0637 \u0627\u0644\u0633\u0646\u0648\u064a\u0629. \u0641\u064a \u0628\u064a\u0626\u0629 \u0627\u062a\u062e\u0627\u0630 \u0627\u0644\u0642\u0631\u0627\u0631 \u0641\u064a \u062c\u0632\u0621 \u0645\u0646 \u0627\u0644\u062b\u0627\u0646\u064a\u0629 \u0647\u0630\u0647\u060c \u064a\u0635\u0628\u062d \u062a\u0635\u0645\u064a\u0645 \u062c\u062f\u0648\u0644 \u0627\u0644\u0623\u0633\u0639\u0627\u0631 \u0627\u0644\u062e\u0627\u0635 \u0628\u0643 \u0647\u0648 \u0627\u0644\u0639\u0627\u0645\u0644 \u0627\u0644\u062d\u0627\u0633\u0645 \u0641\u064a \u0627\u0644\u062a\u062d\u0648\u064a\u0644\u0627\u062a.<\/p>\n\n\n\n<p>\u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u062f\u064a\u0631 \u062e\u062f\u0645\u0629 \u0623\u0648 \u0646\u0634\u0627\u0637\u064b\u0627 \u062a\u062c\u0627\u0631\u064a\u064b\u0627 \u0642\u0627\u0626\u0645\u064b\u0627 \u0639\u0644\u0649 \u0627\u0644\u0627\u0634\u062a\u0631\u0627\u0643\u060c \u0641\u064a\u062c\u0628 \u0623\u0646 \u064a\u0642\u0648\u0645 \u062c\u062f\u0648\u0644 \u0627\u0644\u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u062e\u0627\u0635 \u0628\u0643 \u0628\u0623\u0643\u062b\u0631 \u0645\u0646 \u0645\u062c\u0631\u062f \u0633\u0631\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u062a\u062d\u0648\u064a\u0644 \u0627\u0644\u0632\u0648\u0627\u0631 \u0625\u0644\u0649 \u0639\u0645\u0644\u0627\u0621 \u064a\u062f\u0641\u0639\u0648\u0646. \u064a\u062c\u0628 \u0623\u0646 \u064a\u0648\u062c\u0647 \u0627\u0644\u0627\u0646\u062a\u0628\u0627\u0647\u060c \u0648\u064a\u062f\u0639\u0645 \u0627\u0644\u0645\u0642\u0627\u0631\u0646\u0627\u062a\u060c \u0648\u064a\u062c\u0639\u0644 \u0627\u0644\u062e\u0637\u0629 \u0627\u0644\u0623\u0641\u0636\u0644 \u062a\u0628\u062f\u0648 \u0648\u0643\u0623\u0646\u0647\u0627 \u0627\u0644\u062e\u064a\u0627\u0631 \u0627\u0644\u0648\u0627\u0636\u062d.<\/p>\n\n\n\n<p>\u064a\u062d\u0648\u0644 \u062c\u062f\u0648\u0644 \u0627\u0644\u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u0645\u0635\u0645\u0645 \u0628\u0634\u0643\u0644 \u062c\u064a\u062f \u0645\u0639 \u0645\u0641\u062a\u0627\u062d \u062a\u0628\u062f\u064a\u0644 \u0634\u0647\u0631\u064a\/\u0633\u0646\u0648\u064a \u062c\u062f\u0648\u0644 \u0627\u0644\u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u0642\u064a\u0627\u0633\u064a \u0625\u0644\u0649 \u0634\u064a\u0621 \u0623\u0643\u062b\u0631 \u062f\u064a\u0646\u0627\u0645\u064a\u0643\u064a\u0629 \u0648\u062a\u0631\u0643\u064a\u0632\u064b\u0627 \u0639\u0644\u0649 \u0627\u0644\u0645\u0633\u062a\u062e\u062f\u0645. \u0641\u0647\u0648 \u0644\u0627 \u064a\u0643\u062a\u0641\u064a \u0628\u0639\u0631\u0636 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0641\u062d\u0633\u0628\u060c \u0628\u0644 \u064a\u0648\u062c\u0651\u0647 \u0627\u0644\u0639\u064a\u0646 \u0628\u0634\u0643\u0644 \u0641\u0639\u0627\u0644\u060c \u0648\u064a\u0624\u0643\u062f \u0639\u0644\u0649 \u0627\u0644\u062a\u0648\u0641\u064a\u0631\u060c \u0648\u064a\u0632\u064a\u0644 \u0627\u0644\u0627\u062d\u062a\u0643\u0627\u0643 \u0641\u064a \u0627\u0644\u0645\u0642\u0627\u0631\u0646\u0629.<\/p>\n\n\n\n<p>\u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u062f\u0644\u064a\u0644\u060c \u0633\u062a\u062a\u0639\u0644\u0645 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u062f\u0644\u064a\u0644 \u0643\u064a\u0641\u064a\u0629 \u0625\u0646\u0634\u0627\u0621 \u062a\u0628\u062f\u064a\u0644 \u062a\u0633\u0639\u064a\u0631 \u0634\u0647\u0631\u064a \u0648\u0633\u0646\u0648\u064a \u0646\u0638\u064a\u0641 \u0641\u064a \u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u062a\u0646\u0633\u064a\u0642 \u062c\u062f\u0648\u0644 \u064a\u0628\u062f\u0648 \u0631\u0627\u0626\u0639\u064b\u0627 \u0639\u0644\u0649 \u0623\u064a \u062c\u0647\u0627\u0632.<\/p>\n\n\n\n<div class=\"wp-block-cover aligncenter has-custom-content-position is-position-top-center is-style-default\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-container-core-cover-is-layout-f5f3bcb8 wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\">\u062a\u0628\u062f\u064a\u0644 \u0627\u0644\u0623\u0633\u0639\u0627\u0631 \u0627\u0644\u0634\u0647\u0631\u064a\u0629\/\u0627\u0644\u0633\u0646\u0648\u064a\u0629<\/p>\n\n\n\n<div class=\"wp-block-tableberg-pro-toggle\"><figure class='wp-block-tableberg'>\n                <div class='tableberg-table-wrapper'>\n                    <table\n                        class='wp-block-tableberg tableberg-has-cell-spacing tableberg-cell-spacing-vertical-zero'\n                        style='border-collapse: separate; border-spacing: 2px 0; width: 100%;'\n                        data-tableberg-sortable='false'\n                        data-tableberg-columns='[]'\n                        data-tableberg-pagination='{\"enabled\":false,\"pageSize\":10,\"showPageNumbers\":true,\"showPrevNext\":true}'\n                        data-tableberg-search-enabled='false'\n                        data-tableberg-search-placeholder='Search...'\n                        data-tableberg-search-position='left'\n                        data-tableberg-search-highlight-color=''\n                        data-tableberg-header='true'\n                        data-tableberg-footer='false'\n                        \n                    >\n                        <tbody>\n                            <tr data-tableberg-row='0'><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#2692b9;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='0'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1.38rem'>\n                \u0623\u0633\u0627\u0633\u064a\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#5b0fbf;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='0'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1rem'>\n                \u0645\u062d\u062a\u0631\u0641\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#2692b9;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='0'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1.38rem'>\n                \u0645\u064e\u0634\u0631\u064f\u0648\u0639\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><\/tr><tr data-tableberg-row='1'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0644\u0623\u0641\u0631\u0627\u062f\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                \u0644\u0644\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u0646\u0627\u0634\u0626\u0629\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0644\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u0643\u0628\u0631\u0649\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='2'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $99\/\u0634\u0647\u0631\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $199\/\u0634\u0647\u0631\u064a\u0627\u064b\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $299\/\u0634\u0647\u0631\u064a\u0627\u064b\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='3'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='3'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u062c\u0645\u064a\u0639 \u0645\u064a\u0632\u0627\u062a \u0627\u0644\u062a\u062d\u0644\u064a\u0644\u0627\u062a\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 250,000 \u0632\u064a\u0627\u0631\u0629 \u0645\u062a\u062a\u0628\u0639\u0629\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0627\u0644\u062f\u0639\u0645 \u0627\u0644\u0639\u0627\u062f\u064a\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 3 \u0645\u0646 \u0623\u0639\u0636\u0627\u0621 \u0627\u0644\u0641\u0631\u064a\u0642\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='3'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                \u062c\u0645\u064a\u0639 \u0645\u064a\u0632\u0627\u062a \u0627\u0644\u062a\u062d\u0644\u064a\u0644\u0627\u062a\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 1,000,000 \u0632\u064a\u0627\u0631\u0629 \u062a\u0645 \u062a\u062a\u0628\u0639\u0647\u0627\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                \u062f\u0639\u0645 \u0645\u062a\u0645\u064a\u0632\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 10 \u0623\u0639\u0636\u0627\u0621 \u0645\u0646 \u0627\u0644\u0641\u0631\u064a\u0642\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='3'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u062c\u0645\u064a\u0639 \u0645\u064a\u0632\u0627\u062a \u0627\u0644\u062a\u062d\u0644\u064a\u0644\u0627\u062a\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 5,000,000 \u0632\u064a\u0627\u0631\u0629 \u062a\u0645 \u062a\u062a\u0628\u0639\u0647\u0627\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0627\u0644\u062f\u0639\u0645 \u0627\u0644\u0645\u062e\u0635\u0635\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 50 \u0639\u0636\u0648\u064b\u0627 \u0641\u064a \u0627\u0644\u0641\u0631\u064a\u0642\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='4'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    \u0627\u0628\u062f\u0623\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    \u0627\u0628\u062f\u0623\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    \u0627\u0628\u062f\u0623\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr>\n                        <\/tbody>\n                    <\/table>\n                <\/div>\n                \n            <\/figure>\n\n<figure class='wp-block-tableberg'>\n                <div class='tableberg-table-wrapper'>\n                    <table\n                        class='wp-block-tableberg tableberg-has-cell-spacing tableberg-cell-spacing-vertical-zero'\n                        style='border-collapse: separate; border-spacing: 2px 0; width: 100%;'\n                        data-tableberg-sortable='false'\n                        data-tableberg-columns='[]'\n                        data-tableberg-pagination='{\"enabled\":false,\"pageSize\":10,\"showPageNumbers\":true,\"showPrevNext\":true}'\n                        data-tableberg-search-enabled='false'\n                        data-tableberg-search-placeholder='Search...'\n                        data-tableberg-search-position='left'\n                        data-tableberg-search-highlight-color=''\n                        data-tableberg-header='true'\n                        data-tableberg-footer='false'\n                        \n                    >\n                        <tbody>\n                            <tr data-tableberg-row='0'><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#2692b9;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:60px;min-height:60px'\n                data-cell-row='0'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1.38rem'>\n                \u0623\u0633\u0627\u0633\u064a\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#5b0fbf;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:60px;min-height:60px'\n                data-cell-row='0'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1rem'>\n                \u0645\u062d\u062a\u0631\u0641\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#2692b9;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:60px;min-height:60px'\n                data-cell-row='0'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1.38rem'>\n                \u0645\u064e\u0634\u0631\u064f\u0648\u0639\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><\/tr><tr data-tableberg-row='1'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0644\u0623\u0641\u0631\u0627\u062f\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                \u0644\u0644\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u0646\u0627\u0634\u0626\u0629\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0644\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u0643\u0628\u0631\u0649\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='2'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $990\/\u0633\u0646\u0629\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $1990\/1990\/\u0633\u0646\u0629\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $2990\/\u0633\u0646\u0629\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='3'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:0px;min-height:0px'\n                data-cell-row='3'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u062c\u0645\u064a\u0639 \u0645\u064a\u0632\u0627\u062a \u0627\u0644\u062a\u062d\u0644\u064a\u0644\u0627\u062a\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 250,000 \u0632\u064a\u0627\u0631\u0629 \u0645\u062a\u062a\u0628\u0639\u0629\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0627\u0644\u062f\u0639\u0645 \u0627\u0644\u0639\u0627\u062f\u064a\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 3 \u0645\u0646 \u0623\u0639\u0636\u0627\u0621 \u0627\u0644\u0641\u0631\u064a\u0642\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:0px;min-height:0px'\n                data-cell-row='3'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                \u062c\u0645\u064a\u0639 \u0645\u064a\u0632\u0627\u062a \u0627\u0644\u062a\u062d\u0644\u064a\u0644\u0627\u062a\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 1,000,000 \u0632\u064a\u0627\u0631\u0629 \u062a\u0645 \u062a\u062a\u0628\u0639\u0647\u0627\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                \u062f\u0639\u0645 \u0645\u062a\u0645\u064a\u0632\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 10 \u0623\u0639\u0636\u0627\u0621 \u0645\u0646 \u0627\u0644\u0641\u0631\u064a\u0642\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:0px;min-height:0px'\n                data-cell-row='3'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u062c\u0645\u064a\u0639 \u0645\u064a\u0632\u0627\u062a \u0627\u0644\u062a\u062d\u0644\u064a\u0644\u0627\u062a\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 5,000,000 \u0632\u064a\u0627\u0631\u0629 \u062a\u0645 \u062a\u062a\u0628\u0639\u0647\u0627\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0627\u0644\u062f\u0639\u0645 \u0627\u0644\u0645\u062e\u0635\u0635\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                \u0645\u0627 \u064a\u0635\u0644 \u0625\u0644\u0649 50 \u0639\u0636\u0648\u064b\u0627 \u0641\u064a \u0627\u0644\u0641\u0631\u064a\u0642\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='4'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    \u0627\u0628\u062f\u0623\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    \u0627\u0628\u062f\u0623\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    \u0627\u0628\u062f\u0623\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr>\n                        <\/tbody>\n                    <\/table>\n                <\/div>\n                \n            <\/figure><\/div>\n\n\n\n<p class=\"has-text-align-right has-text-color has-link-color has-x-small-font-size wp-elements-e6213d2371abd0098c7eb5ddc3b9b893\" style=\"border-style:none;border-width:0px;color:#55a3bd;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\"><a href=\"https:\/\/wordpress.org\/plugins\/tableberg\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0645\u062f\u0645\u062c \u0645\u0639 Tableberg<\/a><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0643\u064a\u0641\u064a\u0629 \u0625\u0636\u0627\u0641\u0629 \u062a\u0628\u062f\u064a\u0644 \u062a\u0633\u0639\u064a\u0631 \u0634\u0647\u0631\u064a\/\u0633\u0646\u0648\u064a \u0641\u064a \u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633<\/strong><\/h2>\n\n\n\n<p>\u0648\u0627\u0644\u0622\u0646 \u0628\u0639\u062f \u0623\u0646 \u0639\u0631\u0641\u062a \u0643\u064a\u0641 \u064a\u0633\u0627\u0639\u062f \u062a\u0628\u062f\u064a\u0644 \u0627\u0644\u062a\u0633\u0639\u064a\u0631 \u0641\u064a \u062a\u0628\u0633\u064a\u0637 \u0627\u0644\u0645\u0642\u0627\u0631\u0646\u0627\u062a \u0648\u0625\u0628\u0631\u0627\u0632 \u0627\u0644\u0642\u064a\u0645\u0629\u060c \u062f\u0639\u0646\u0627 \u0646\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u062e\u0637\u0648\u0627\u062a \u0625\u0646\u0634\u0627\u0621 \u0648\u0627\u062d\u062f\u0629 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0625\u0636\u0627\u0641\u0629 Tableberg.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0627\u0644\u062e\u0637\u0648\u0629 1: \u062a\u062b\u0628\u064a\u062a \u0648\u062a\u0641\u0639\u064a\u0644 Tableberg<\/strong><\/h3>\n\n\n\n<p>\u062a\u0648\u062c\u064e\u0651\u0647 \u0625\u0644\u0649 \u0644\u0648\u062d\u0629 \u062a\u062d\u0643\u0645 \u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633\u060c \u0648\u0627\u0646\u062a\u0642\u0644 \u0625\u0644\u0649 \u0627\u0644\u0625\u0636\u0627\u0641\u0627\u062a \u2190 \u0625\u0636\u0627\u0641\u0629 \u062c\u062f\u064a\u062f\u060c \u0648\u0627\u0628\u062d\u062b \u0639\u0646 Tableberg\u060c \u062b\u0645 \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u062a\u062b\u0628\u064a\u062a \u0627\u0644\u0622\u0646\u060c \u062b\u0645 \u062a\u0641\u0639\u064a\u0644. \u0628\u0645\u062c\u0631\u062f \u0627\u0644\u062a\u0641\u0639\u064a\u0644\u060c \u0633\u062a\u062c\u062f \u0645\u0643\u0648\u0650\u0651\u0646\u064a\u0646 \u062c\u062f\u064a\u062f\u064a\u0646 \u0641\u064a \u0627\u0644\u0645\u062d\u0631\u0650\u0651\u0631: Tableberg \u0648Toggle \u0644\u0640 Tableberg.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"415\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new-1024x415.png\" alt=\"\" class=\"has-border-color wp-image-8629\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new-1024x415.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new-300x122.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new-768x312.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new-18x7.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new.png 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_9f5958f1-8c4c-4765-95e3-a9826d69c747\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0627\u0644\u062e\u0637\u0648\u0629 2: \u0625\u0636\u0627\u0641\u0629 \u0627\u0644\u062a\u0628\u062f\u064a\u0644 \u0644\u0643\u062a\u0644\u0629 Tableberg<\/strong><\/h3>\n\n\n\n<p>\u0627\u0641\u062a\u062d \u0627\u0644\u0645\u0642\u0627\u0644\u0629 \u0623\u0648 \u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u062a\u064a \u062a\u0631\u064a\u062f \u0648\u0636\u0639 \u062c\u062f\u0648\u0644 \u0627\u0644\u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u062e\u0627\u0635 \u0628\u0643 \u0641\u064a\u0647\u0627. \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0623\u064a\u0642\u0648\u0646\u0629 \u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062c\u0645\u0639\u060c \u0648\u0627\u0628\u062d\u062b \u0639\u0646 Toggle \u0644\u0640 Tableberg\u060c \u0648\u0623\u062f\u0631\u062c \u0627\u0644\u0645\u0643\u0648\u0650\u0651\u0646. \u064a\u0628\u062f\u0623 \u0628\u062b\u0644\u0627\u062b \u0639\u0644\u0627\u0645\u0627\u062a \u062a\u0628\u0648\u064a\u0628 \u0628\u0634\u0643\u0644 \u0627\u0641\u062a\u0631\u0627\u0636\u064a. \u0645\u0631\u0650\u0651\u0631 \u0641\u0648\u0642 \u0623\u064a \u0639\u0644\u0627\u0645\u0629 \u062a\u0628\u0648\u064a\u0628 \u0644\u0625\u0632\u0627\u0644\u062a\u0647\u0627\u060c \u0623\u0648 \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062c\u0645\u0639 \u0644\u0625\u0636\u0627\u0641\u0629 \u0627\u0644\u0645\u0632\u064a\u062f. \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0625\u0644\u0649 \u0647\u0630\u0627 \u0627\u0644\u0625\u0639\u062f\u0627\u062f\u060c \u0627\u062d\u062a\u0641\u0638 \u0628\u0639\u0644\u0627\u0645\u062a\u064a \u062a\u0628\u0648\u064a\u0628 \u0641\u0642\u0637 - \u0648\u0627\u062d\u062f\u0629 \u0644\u0640 \"\u0634\u0647\u0631\u064a\u064b\u0627\" \u0648\u0627\u0644\u0623\u062e\u0631\u0649 \u0644\u0640 \"\u0633\u0646\u0648\u064a\u064b\u0627\".<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"454\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-1024x454.png\" alt=\"\" class=\"has-border-color wp-image-8724\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-1024x454.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-300x133.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-768x340.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-1536x681.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-18x8.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2.png 1791w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_ba951f5b-ed3e-42ee-ac13-c66dff4e4fd2\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0627\u0644\u062e\u0637\u0648\u0629 3: \u062a\u0643\u0648\u064a\u0646 \u0625\u0639\u062f\u0627\u062f\u0627\u062a \u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u0628\u0648\u064a\u0628<\/strong><\/h3>\n\n\n\n<p>\u0645\u0639 \u062a\u062d\u062f\u064a\u062f \u0627\u0644\u0645\u0643\u0648\u0650\u0651\u0646\u060c \u0627\u0633\u062a\u062e\u062f\u0645 \u0644\u0648\u062d\u0629 \u0627\u0644\u0625\u0639\u062f\u0627\u062f\u0627\u062a \u0627\u0644\u0645\u0648\u062c\u0648\u062f\u0629 \u0639\u0644\u0649 \u0627\u0644\u064a\u0645\u064a\u0646 \u0644\u0636\u0628\u0637 \u0643\u0644 \u0645\u0646 \u0627\u0644\u062e\u064a\u0627\u0631\u064a\u0646 \u0627\u0644\u0639\u0627\u0645 \u0648\u0627\u0644\u0646\u0645\u0637.<\/p>\n\n\n\n<p>\u0641\u064a \u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u0628\u0648\u064a\u0628 \u0639\u0627\u0645\u060c \u0642\u0645 \u0628\u0625\u0639\u0627\u062f\u0629 \u062a\u0633\u0645\u064a\u0629 \u0643\u0644 \u0639\u0644\u0627\u0645\u0629 \u062a\u0628\u0648\u064a\u0628\u060c \u0648\u0627\u062e\u062a\u0631 \u0623\u064a \u0639\u0644\u0627\u0645\u0629 \u062a\u0628\u0648\u064a\u0628 \u0646\u0634\u0637\u0629 \u0627\u0641\u062a\u0631\u0627\u0636\u064a\u064b\u0627\u060c \u0648\u0642\u0645 \u0628\u0645\u062d\u0627\u0630\u0627\u0629 \u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u062a\u0628\u0648\u064a\u0628 \u062d\u0633\u0628 \u0627\u0644\u062d\u0627\u062c\u0629. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-1024x509.png\" alt=\"\" class=\"has-border-color wp-image-8725\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-1024x509.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-300x149.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-768x381.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-1536x763.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-18x9.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1.png 1760w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u0636\u0645\u0646 \u0627\u0644\u0646\u0645\u0637\u060c \u064a\u0645\u0643\u0646\u0643 \u0636\u0628\u0637 \u0627\u0644\u0623\u0644\u0648\u0627\u0646 \u0644\u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u062a\u0628\u0648\u064a\u0628 \u0627\u0644\u0646\u0634\u0637\u0629 \u0648\u063a\u064a\u0631 \u0627\u0644\u0646\u0634\u0637\u0629\u060c \u0648\u062a\u0639\u064a\u064a\u0646 \u0627\u0644\u0645\u0633\u0627\u0641\u0627\u062a \u0623\u0633\u0641\u0644 \u0645\u0641\u062a\u0627\u062d \u0627\u0644\u062a\u0628\u062f\u064a\u0644\u060c \u0648\u062a\u0639\u062f\u064a\u0644 \u0646\u0635\u0641 \u0642\u0637\u0631 \u0627\u0644\u062d\u062f\u0648\u062f \u0644\u062a\u0642\u0631\u064a\u0628 \u0627\u0644\u0632\u0648\u0627\u064a\u0627 \u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u0631\u064a\u062f \u0645\u0638\u0647\u0631\u064b\u0627 \u0623\u0643\u062b\u0631 \u0646\u0639\u0648\u0645\u0629.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"564\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-1024x564.png\" alt=\"\" class=\"has-border-color wp-image-8726\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-1024x564.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-300x165.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-768x423.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-1536x846.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-18x10.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1.png 1744w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_3c8aeef2-8a17-427b-b2ca-bc3d2521baa2\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0627\u0644\u062e\u0637\u0648\u0629 4: \u0625\u0636\u0627\u0641\u0629 \u062c\u062f\u0627\u0648\u0644 \u062f\u0627\u062e\u0644 \u0643\u0644 \u0639\u0644\u0627\u0645\u0629 \u062a\u0628\u0648\u064a\u0628<\/strong><\/h3>\n\n\n\n<p>\u0627\u0646\u0642\u0631 \u0641\u064a \u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u0628\u0648\u064a\u0628 \u0627\u0644\u0623\u0648\u0644\u0649 \u0648\u0623\u0646\u0634\u0626 \u0627\u0644\u062c\u062f\u0648\u0644. \u0633\u064a\u062d\u062a\u0648\u064a \u0647\u0630\u0627 \u0639\u0644\u0649 \u062c\u062f\u0648\u0644 \u0627\u0644\u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u0634\u0647\u0631\u064a \u0627\u0644\u062e\u0627\u0635 \u0628\u0643. \u0643\u0631\u0631 \u0627\u0644\u0623\u0645\u0631 \u0646\u0641\u0633\u0647 \u062f\u0627\u062e\u0644 \u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u0628\u0648\u064a\u0628 \u0627\u0644\u062b\u0627\u0646\u064a\u0629 \u0648\u0623\u0636\u0641 \u0646\u0633\u062e\u062a\u0643 \u0627\u0644\u0633\u0646\u0648\u064a\u0629. \u064a\u062c\u0628 \u0623\u0646 \u062a\u0638\u0644 \u0627\u0644\u0628\u0646\u064a\u0629 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643 \u0644\u0643\u0644\u0627 \u0627\u0644\u062c\u062f\u0648\u0644\u064a\u0646 \u0643\u0645\u0627 \u0647\u064a\u060c \u0645\u0639 \u062a\u063a\u064a\u064a\u0631 \u0627\u0644\u062a\u0633\u0639\u064a\u0631 \u0648\u0627\u0644\u062a\u0633\u0645\u064a\u0627\u062a \u0630\u0627\u062a \u0627\u0644\u0635\u0644\u0629 \u0641\u0642\u0637.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"500\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-1024x500.png\" alt=\"\" class=\"has-border-color wp-image-8727\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-1024x500.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-300x147.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-768x375.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-1536x750.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-18x9.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2.png 1681w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_ddfc08f8-af64-49b2-ae15-3f4d799fef78\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0627\u0644\u062e\u0637\u0648\u0629 5: \u062a\u062e\u0635\u064a\u0635 \u0627\u0644\u062c\u062f\u0627\u0648\u0644<\/strong><\/h3>\n\n\n\n<p>\u0623\u0636\u0641 \u0623\u0633\u0645\u0627\u0621 \u0627\u0644\u062e\u0637\u0629\u060c \u0648\u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u062c\u0645\u0647\u0648\u0631\u060c \u0648\u0627\u0644\u062a\u0633\u0639\u064a\u0631\u060c \u0648\u0627\u0644\u0645\u064a\u0632\u0627\u062a\u060c \u0648\u0623\u0632\u0631\u0627\u0631 \u0627\u0644\u062d\u062b \u0639\u0644\u0649 \u0627\u062a\u062e\u0627\u0630 \u0625\u062c\u0631\u0627\u0621 \u062f\u0627\u062e\u0644 \u0643\u0644 \u0639\u0645\u0648\u062f. \u0627\u0633\u062a\u062e\u062f\u0645 \u0643\u062a\u0644 \u0627\u0644\u0641\u0642\u0631\u0627\u062a \u0648\u0627\u0644\u0642\u0648\u0627\u0626\u0645 \u0648\u0643\u062a\u0644 \u0627\u0644\u0623\u0632\u0631\u0627\u0631 \u062f\u0627\u062e\u0644 \u062e\u0644\u0627\u064a\u0627 \u0627\u0644\u062c\u062f\u0648\u0644.&nbsp;<\/p>\n\n\n\n<p>\u062b\u0645 \u0627\u0641\u062a\u062d \u0627\u0644\u0625\u0639\u062f\u0627\u062f\u0627\u062a \u0627\u0644\u0639\u0627\u0645\u0629 \u0644\u062a\u0639\u064a\u064a\u0646 \u0631\u0623\u0633 \u0627\u0644\u0635\u0641\u062d\u0629 \u0648\u062a\u0630\u064a\u064a\u0644\u0647\u0627\u060c \u0648\u0627\u0636\u0628\u0637 \u0645\u064a\u0632\u0627\u062a \u0645\u062b\u0644 \u0627\u0644\u0631\u0623\u0633 \u0627\u0644\u0644\u0627\u0635\u0642 \u0648\u0627\u0644\u0641\u0631\u0632 \u0648\u0627\u0644\u0628\u062d\u062b \u0625\u0630\u0627 \u0644\u0632\u0645 \u0627\u0644\u0623\u0645\u0631. \u0623\u062e\u064a\u0631\u064b\u0627\u060c \u0627\u0633\u062a\u062e\u062f\u0645 \u0639\u0644\u0627\u0645\u0629 \u062a\u0628\u0648\u064a\u0628 \u0627\u0644\u0646\u0645\u0637 \u0644\u0636\u0628\u0637 \u0627\u0644\u062a\u0628\u0627\u0639\u062f \u0648\u0623\u0644\u0648\u0627\u0646 \u0627\u0644\u062e\u0644\u0641\u064a\u0629 \u0648\u0627\u0644\u062d\u062f\u0648\u062f \u0648\u0627\u0644\u0645\u062d\u0627\u0630\u0627\u0629 \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0645\u0638\u0647\u0631 \u0646\u0638\u064a\u0641 \u0648\u0645\u062a\u0633\u0642 \u0641\u064a \u0643\u0644\u0627 \u0627\u0644\u062c\u062f\u0648\u0644\u064a\u0646.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"489\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-1024x489.png\" alt=\"\" class=\"has-border-color wp-image-8728\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-1024x489.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-300x143.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-768x367.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-1536x733.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-18x9.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2.png 1825w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_8a54aa64-d7a8-4877-be81-4356468a3997\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0627\u0644\u062e\u0637\u0648\u0629 6: \u0627\u0644\u062d\u0641\u0638 \u0648\u0627\u0644\u0645\u0639\u0627\u064a\u0646\u0629 \u0648\u0627\u0644\u0646\u0634\u0631<\/strong><\/h3>\n\n\n\n<p>\u0644\u0627 \u062a\u0646\u0633\u064e \u062d\u0641\u0638 \u0639\u0645\u0644\u0643 \u0623\u0648\u0644\u0627\u064b. \u0628\u0639\u062f \u0630\u0644\u0643\u060c \u0627\u0633\u062a\u062e\u062f\u0645 \u062e\u064a\u0627\u0631 \u0627\u0644\u0645\u0639\u0627\u064a\u0646\u0629 \u0644\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0634\u0643\u0644 \u0627\u0644\u062a\u0628\u062f\u064a\u0644 \u0627\u0644\u062e\u0627\u0635 \u0628\u0643 \u0639\u0644\u0649 \u0643\u0644 \u0645\u0646 \u0633\u0637\u062d \u0627\u0644\u0645\u0643\u062a\u0628 \u0648\u0627\u0644\u062c\u0648\u0627\u0644. \u062a\u0623\u0643\u062f \u0645\u0646 \u0623\u0646 \u062a\u0628\u062f\u064a\u0644 \u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u062a\u0628\u062f\u064a\u0644 \u0633\u0644\u0633 \u0648\u0623\u0646 \u0643\u0644 \u0646\u0633\u062e\u0629 \u0645\u0646 \u0627\u0644\u062c\u062f\u0648\u0644 \u0648\u0627\u0636\u062d\u0629. \u0628\u0645\u062c\u0631\u062f \u0623\u0646 \u062a\u0634\u0639\u0631 \u0628\u0627\u0644\u0631\u0636\u0627\u060c \u0627\u0636\u063a\u0637 \u0639\u0644\u0649 \u0646\u0634\u0631 \u0644\u062c\u0639\u0644\u0647\u0627 \u0645\u0628\u0627\u0634\u0631\u0629.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"548\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1-1024x548.png\" alt=\"\" class=\"has-border-color wp-image-8729\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1-1024x548.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1-300x161.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1-768x411.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1-18x10.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1.png 1473w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_cd938526-ab9a-4931-afaf-11427927d265\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<p><strong>\u0627\u0644\u0623\u0641\u0643\u0627\u0631 \u0627\u0644\u0646\u0647\u0627\u0626\u064a\u0629<\/strong><\/p>\n\n\n\n<p>\u062a\u0628\u062f\u064a\u0644 \u0627\u0644\u062a\u0633\u0639\u064a\u0631 \u0627\u0644\u0634\u0647\u0631\u064a\/\u0627\u0644\u0633\u0646\u0648\u064a \u0644\u064a\u0633 \u0645\u062c\u0631\u062f \u062e\u062f\u0639\u0629 \u062a\u0635\u0645\u064a\u0645\u064a\u0629. \u0625\u0646\u0647\u0627 \u0637\u0631\u064a\u0642\u0629 \u0639\u0645\u0644\u064a\u0629 \u0644\u062a\u0642\u062f\u064a\u0645 \u062e\u064a\u0627\u0631\u0627\u062a \u0641\u0648\u062a\u0631\u0629 \u0645\u0631\u0646\u0629 \u062f\u0648\u0646 \u0625\u0631\u0628\u0627\u0643 \u062a\u062e\u0637\u064a\u0637\u0643. \u0645\u0639 Tableberg\u060c \u0644\u0646 \u062a\u062d\u062a\u0627\u062c \u0625\u0644\u0649 \u0625\u0636\u0627\u0641\u0627\u062a \u0625\u0636\u0627\u0641\u064a\u0629 \u0623\u0648 \u062a\u0639\u0644\u064a\u0645\u0627\u062a \u0628\u0631\u0645\u062c\u064a\u0629 \u0645\u062e\u0635\u0635\u0629 \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0630\u0644\u0643 \u0628\u0634\u0643\u0644 \u0635\u062d\u064a\u062d. \u064a\u0645\u0643\u0646\u0643 \u0625\u0646\u0634\u0627\u0621 \u062c\u062f\u0648\u0644 \u062a\u0633\u0639\u064a\u0631 \u0633\u0631\u064a\u0639 \u0627\u0644\u0627\u0633\u062a\u062c\u0627\u0628\u0629 \u0648\u062c\u064a\u062f \u0627\u0644\u062a\u0646\u0638\u064a\u0645 \u064a\u0633\u0627\u0639\u062f \u0627\u0644\u0632\u0627\u0626\u0631\u064a\u0646 \u0639\u0644\u0649 \u0645\u0642\u0627\u0631\u0646\u0629 \u0627\u0644\u062e\u0637\u0637 \u0628\u0648\u0636\u0648\u062d \u0648\u0627\u062e\u062a\u064a\u0627\u0631 \u0645\u0627 \u064a\u0646\u0627\u0633\u0628\u0647\u0645 \u0628\u0634\u0643\u0644 \u0623\u0641\u0636\u0644.<\/p>\n\n\n\n<p>\u062e\u0630 \u0627\u0644\u0648\u0642\u062a \u0627\u0644\u0643\u0627\u0641\u064a \u0644\u0625\u0639\u062f\u0627\u062f \u0645\u0641\u062a\u0627\u062d \u0627\u0644\u062a\u0628\u062f\u064a\u0644 \u0628\u0639\u0646\u0627\u064a\u0629\u060c \u0648\u0633\u062a\u062d\u0635\u0644 \u0641\u064a \u0627\u0644\u0646\u0647\u0627\u064a\u0629 \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0623\u0646\u0638\u0641 \u0648\u062a\u062c\u0631\u0628\u0629 \u0627\u062a\u062e\u0627\u0630 \u0642\u0631\u0627\u0631 \u0623\u0643\u062b\u0631 \u0633\u0644\u0627\u0633\u0629 \u0644\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u064a\u0646.<\/p>","protected":false},"excerpt":{"rendered":"<p>Today&#8217;s buyers evaluate options in seconds: some scan prices, others compare features, and many debate monthly versus annual plans. In this split-second decision-making environment, your pricing table&#8217;s design becomes the decisive factor in conversions. If you run a service or subscription-based business, your pricing table needs to do more than list options to convert visitors [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":8700,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[7,130],"tags":[],"class_list":["post-8698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to","category-tableberg"],"featured_image_src":"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/MonthlyYearly-Pricing-Toggle-850-x-335-px.png","author_info":{"display_name":"Moinul Islam","author_link":"https:\/\/tableberg.com\/ar\/author\/marufmoinul27\/"},"_links":{"self":[{"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/posts\/8698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/comments?post=8698"}],"version-history":[{"count":39,"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/posts\/8698\/revisions"}],"predecessor-version":[{"id":8761,"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/posts\/8698\/revisions\/8761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/media\/8700"}],"wp:attachment":[{"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/media?parent=8698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/categories?post=8698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tableberg.com\/ar\/wp-json\/wp\/v2\/tags?post=8698"}],"curies":[{"name":"\u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}