{"id":1169,"date":"2024-04-30T15:32:43","date_gmt":"2024-04-30T15:32:43","guid":{"rendered":"https:\/\/tableberg.com\/?post_type=docs&#038;p=1169"},"modified":"2024-11-11T11:58:50","modified_gmt":"2024-11-11T11:58:50","password":"","slug":"come-rimuovere-una-riga-o-una-colonna-da-una-tabella","status":"publish","type":"docs","link":"https:\/\/tableberg.com\/it\/docs\/how-to-remove-a-row-or-column-from-a-table\/","title":{"rendered":"Remove a Row or Column From a Table"},"content":{"rendered":"<p>Con il passare del tempo, alcune informazioni diventano meno importanti. Pu\u00f2 trattarsi di un semplice paragrafo o di una parte di una tabella di dati. Se si scopre che una riga o una colonna della tabella non \u00e8 pi\u00f9 importante, \u00e8 sufficiente rimuoverla.<\/p>\n\n\n\n<p>Questo articolo di documentazione illustra come rimuovere una riga o una colonna da una tabella creata con il metodo <a href=\"https:\/\/wordpress.org\/plugins\/tableberg\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">TavoloBerg<\/a> plugin.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Passo 01: selezionare la riga che si desidera eliminare<\/h2>\n\n\n\n<p>Selezionare la riga che si desidera eliminare posizionando il cursore su di essa.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"653\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Select-the-Row-You-Want-to-Delete.webp\" alt=\"Selezionare la riga che si desidera eliminare\" class=\"wp-image-1170\" style=\"border-width:1px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Select-the-Row-You-Want-to-Delete.webp 1280w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Select-the-Row-You-Want-to-Delete-300x153.webp 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Select-the-Row-You-Want-to-Delete-1024x522.webp 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Select-the-Row-You-Want-to-Delete-768x392.webp 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Passo 02: utilizzare l'opzione Elimina riga<\/h2>\n\n\n\n<p>Fare clic sul pulsante <strong>Modifica tabella<\/strong> sulla barra degli strumenti. Verr\u00e0 visualizzato il pulsante <strong>Cancellare la riga<\/strong> nell'elenco.<\/p>\n\n\n\n<p>Premendo il tasto <strong>Cancellare la riga<\/strong> \u00e8 possibile rimuovere la rispettiva riga dalla tabella.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"653\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Use-the-Delete-Row-Option.webp\" alt=\"Utilizzare l&#039;opzione Elimina riga\" class=\"wp-image-1171\" style=\"border-width:1px;border-radius:3px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Use-the-Delete-Row-Option.webp 1280w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Use-the-Delete-Row-Option-300x153.webp 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Use-the-Delete-Row-Option-1024x522.webp 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Use-the-Delete-Row-Option-768x392.webp 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Passo 03: selezionare la colonna da eliminare<\/h2>\n\n\n\n<p>Allo stesso modo, selezionare la colonna che si desidera eliminare posizionando il cursore su di essa.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"653\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Select-the-Column-You-Want-to-Delete.webp\" alt=\"Selezionare la colonna da eliminare\" class=\"wp-image-1172\" style=\"border-width:1px;border-radius:3px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Select-the-Column-You-Want-to-Delete.webp 1280w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Select-the-Column-You-Want-to-Delete-300x153.webp 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Select-the-Column-You-Want-to-Delete-1024x522.webp 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Select-the-Column-You-Want-to-Delete-768x392.webp 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Passo 04: utilizzare l'opzione Elimina colonna <\/h2>\n\n\n\n<p>Fare clic sul pulsante <strong>Icona di modifica della tabella<\/strong>. Vedrete il <strong>Cancellare la colonna<\/strong> opzione. <\/p>\n\n\n\n<p>Facendo clic sul pulsante <strong>Cancellare la colonna<\/strong> \u00e8 possibile rimuovere facilmente la rispettiva colonna dalla tabella.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"653\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Use-the-Delete-Column-Option-.webp\" alt=\"Utilizzare l&#039;opzione Elimina colonna \" class=\"wp-image-1173\" style=\"border-width:1px;border-radius:3px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Use-the-Delete-Column-Option-.webp 1280w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Use-the-Delete-Column-Option--300x153.webp 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Use-the-Delete-Column-Option--1024x522.webp 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/04\/Use-the-Delete-Column-Option--768x392.webp 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<p>Ci auguriamo che questa esercitazione vi abbia soddisfatto. D'ora in poi sarete in grado di rimuovere da soli le righe e le colonne dalla vostra tabella.<\/p>\n\n\n\n<p>Potete esplorare anche questo post <a href=\"https:\/\/tableberg.com\/it\/documenti\/tableberg-one\/tavolo-di-lavoro\/how-to-add-table-borders\/\" target=\"_blank\" rel=\"noreferrer noopener\">come aggiungere righe e colonne a una tabella in WordPress<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Over the passage of time, some information gets less important. It could be a plain paragraph or some part of a data table. If you ever find that a row or a column of your table is no longer important, you can simply remove it. This documentation article will show you how to remove a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"doc_category":[126],"doc_tag":[50],"class_list":["post-1169","docs","type-docs","status-publish","hentry","doc_category-functionality-controls","doc_tag-table-rows-and-columns"],"year_month":"2026-05","word_count":229,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Istiak Rayhan","author_nicename":"wpx_irayhan","author_url":"https:\/\/tableberg.com\/it\/author\/wpx_irayhan\/"},"doc_category_info":[{"term_name":"Functionality &amp; Controls","term_url":"https:\/\/tableberg.com\/it\/docs-category\/functionality-controls\/"}],"doc_tag_info":[{"term_name":"Table Rows and Columns","term_url":"https:\/\/tableberg.com\/it\/docs-tag\/table-rows-and-columns\/"}],"_links":{"self":[{"href":"https:\/\/tableberg.com\/it\/wp-json\/wp\/v2\/docs\/1169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tableberg.com\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/tableberg.com\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/tableberg.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tableberg.com\/it\/wp-json\/wp\/v2\/comments?post=1169"}],"version-history":[{"count":2,"href":"https:\/\/tableberg.com\/it\/wp-json\/wp\/v2\/docs\/1169\/revisions"}],"predecessor-version":[{"id":2246,"href":"https:\/\/tableberg.com\/it\/wp-json\/wp\/v2\/docs\/1169\/revisions\/2246"}],"wp:attachment":[{"href":"https:\/\/tableberg.com\/it\/wp-json\/wp\/v2\/media?parent=1169"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/tableberg.com\/it\/wp-json\/wp\/v2\/doc_category?post=1169"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/tableberg.com\/it\/wp-json\/wp\/v2\/doc_tag?post=1169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}