{"id":138,"date":"2025-03-31T03:24:00","date_gmt":"2025-03-31T03:24:00","guid":{"rendered":"https:\/\/tableberg.com\/?p=138"},"modified":"2025-03-31T03:24:03","modified_gmt":"2025-03-31T03:24:03","slug":"como-criar-uma-tabela-no-wordpress","status":"publish","type":"post","link":"https:\/\/tableberg.com\/pt\/how-to-create-a-table-in-wordpress\/","title":{"rendered":"Como criar uma tabela no WordPress (sem um plug-in)"},"content":{"rendered":"<p>Uma tabela \u00e9 um conjunto de linhas e colunas que ajudam a organizar e exibir dados em um formato estruturado. Elas permitem que voc\u00ea apresente os dados mais importantes de forma clara e concisa para que os leitores possam localiz\u00e1-los e analis\u00e1-los rapidamente sem confus\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m disso, as tabelas permitem que voc\u00ea mantenha um layout consistente e organizado para apresentar informa\u00e7\u00f5es em um site. As tabelas s\u00e3o usadas principalmente para cobrir compara\u00e7\u00f5es de pre\u00e7os, listagem de recursos, agendamento de eventos e muito mais.<\/p>\n\n\n\n<p>O WordPress \u00e9 um maravilhoso construtor de sites que, por padr\u00e3o, coloca v\u00e1rios elementos na ponta de seus dedos. Ele oferece uma maneira padr\u00e3o de criar tabelas completas em seu site. Vamos explorar como criar uma tabela no WordPress sem plug-ins.<\/p>\n\n\n<div data-is_sticky=\"false\" data-sticky_toc_position=\"left\" data-hide_sticky_on_mobile=\"false\" data-sticky_button_icon='&lt;svg style=\"color:#000000;\" class=\"ub_sticky-toc-open-button-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"34px\" width=\"34px\" viewBox=\"0, 0, 448, 512\"&gt;&lt;path fill=\"currentColor\" d=\"M0 96C0 78.33 14.33 64 32 64H416C433.7 64 448 78.33 448 96C448 113.7 433.7 128 416 128H32C14.33 128 0 113.7 0 96zM0 256C0 238.3 14.33 224 32 224H416C433.7 224 448 238.3 448 256C448 273.7 433.7 288 416 288H32C14.33 288 0 273.7 0 256zM416 448H32C14.33 448 0 433.7 0 416C0 398.3 14.33 384 32 384H416C433.7 384 448 398.3 448 416C448 433.7 433.7 448 416 448z\"&gt;&lt;\/svg&gt;' data-sticky_button_color=\"#000000\" data-sticky_toc_width=\"320px\" class=\"wp-block-ub-table-of-contents-block ub_table-of-contents\" id=\"ub_table-of-contents-bf299251-a07d-4149-a51e-b25a68a3de97\" data-linktodivider=\"false\" data-showtext=\"show\" data-hidetext=\"hide\" data-scrolltype=\"auto\" data-enablesmoothscroll=\"false\" data-initiallyhideonmobile=\"false\" data-initiallyshow=\"true\"><div class=\"ub_table-of-contents-header-container\" style=\"\">\n\t\t\t<div class=\"ub_table-of-contents-header\" style=\"text-align: left; \">\n\t\t\t\t<div class=\"ub_table-of-contents-title\" style=\"\">\u00cdndice:<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div><div class=\"ub_table-of-contents-extra-container\" style=\"\">\n\t\t\t<div class=\"ub_table-of-contents-container ub_table-of-contents-1-column\">\n\t\t\t\t<ul style=\"\"><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-table-in-wordpress\/#0-step-01-open-a-postpage-and-add-the-table-block\" style=\"\">Etapa 01: Abra uma postagem\/p\u00e1gina e adicione o bloco de tabela<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-table-in-wordpress\/#1-step-2-specify-the-column-and-row-number\" style=\"\">Etapa 2: Especifique o n\u00famero da coluna e da linha<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-table-in-wordpress\/#2-step-3-increase-or-delete-the-existing-table-rows-and-columns-\" style=\"\">Etapa 3: Aumentar ou excluir as linhas e colunas da tabela existente\u00a0<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-table-in-wordpress\/#3-step-4-add-header-and-footer-to-the-table\" style=\"\">Etapa 4: Adicionar cabe\u00e7alho e rodap\u00e9 \u00e0 tabela<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-table-in-wordpress\/#4-step-5-stylize-the-table\" style=\"\">Etapa 5: Estilize a mesa<\/a><\/li><\/ul>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n<div class=\"wp-block-group has-border-color has-global-padding is-layout-constrained wp-container-core-group-is-layout-8db5ca72 wp-block-group-is-layout-constrained\" style=\"border-color:#671feb;border-style:solid;border-width:1px;border-radius:4px;padding-top:var(--wp--preset--spacing--medium);padding-right:var(--wp--preset--spacing--small);padding-bottom:var(--wp--preset--spacing--medium);padding-left:var(--wp--preset--spacing--small)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-505d3e6d wp-block-group-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--small);padding-bottom:var(--wp--preset--spacing--small)\">\n<p style=\"font-size:clamp(18.959px, 1.185rem + ((1vw - 3.2px) * 1.175), 30px);\"><strong>Criar mesas bonitas <\/strong><br><strong>Com o Block Editor<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-f2baa792 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/wordpress.org\/plugins\/tableberg\/\" style=\"background-color:#671feb\" target=\"_blank\" rel=\"noreferrer noopener\">Experimente gratuitamente<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/tableberg.com\/pt\/precificacao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Obter um profissional<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/05\/Tableberg.png\" alt=\"\" class=\"wp-image-1545\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/05\/Tableberg.png 540w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/05\/Tableberg-300x300.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/05\/Tableberg-150x150.png 150w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"0-step-01-open-a-postpage-and-add-the-table-block\">Etapa 01: Abra uma postagem\/p\u00e1gina e adicione o bloco de tabela<\/h2>\n\n\n\n<p>V\u00e1 para o post\/p\u00e1gina em que voc\u00ea deseja adicionar uma tabela. <\/p>\n\n\n\n<p>Quando voc\u00ea estiver no Editor, clique no \u00edcone <strong>Mais (+)<\/strong> \u00edcone e tipo <strong>Tabela<\/strong> na caixa de pesquisa. Em seguida, clique no bloco Table para inseri-lo.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"654\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-the-Table-block-to-your-post-or-page.png\" alt=\"Adicione o bloco Table ao seu post ou p\u00e1gina\" class=\"has-border-color wp-image-139\" style=\"border-color:#671feb;border-width:1px;border-radius:4px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-the-Table-block-to-your-post-or-page.png 1280w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-the-Table-block-to-your-post-or-page-300x153.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-the-Table-block-to-your-post-or-page-1024x523.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-the-Table-block-to-your-post-or-page-768x392.png 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-step-2-specify-the-column-and-row-number\">Etapa 2: Especifique o n\u00famero da coluna e da linha<\/h2>\n\n\n\n<p>Voc\u00ea ter\u00e1 a op\u00e7\u00e3o de especificar o n\u00famero da coluna e da linha. Quando terminar, pressione o bot\u00e3o <strong>Criar tabela<\/strong> bot\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"654\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Specify-the-column-and-row-number.png\" alt=\"Especifique o n\u00famero da coluna e da linha\" class=\"has-border-color wp-image-140\" style=\"border-color:#671feb;border-width:1px;border-radius:4px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Specify-the-column-and-row-number.png 1280w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Specify-the-column-and-row-number-300x153.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Specify-the-column-and-row-number-1024x523.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Specify-the-column-and-row-number-768x392.png 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<p>Agora, adicione conte\u00fado \u00e0 tabela como voc\u00ea faz nas tabelas normais do Microsoft Offices.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"654\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-content-to-the-table.png\" alt=\"Adicionar conte\u00fado \u00e0 tabela\" class=\"has-border-color wp-image-141\" style=\"border-color:#671feb;border-width:1px;border-radius:4px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-content-to-the-table.png 1280w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-content-to-the-table-300x153.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-content-to-the-table-1024x523.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-content-to-the-table-768x392.png 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"2-step-3-increase-or-delete-the-existing-table-rows-and-columns-\">Etapa 3: Aumentar ou excluir as linhas e colunas da tabela existente&nbsp;<\/h2>\n\n\n\n<p>Pressione o bot\u00e3o <strong>Editar tabela<\/strong> na barra de ferramentas. Voc\u00ea ver\u00e1 uma lista suspensa. Voc\u00ea pode <a href=\"https:\/\/tableberg.com\/pt\/como-adicionar-uma-linha-a-uma-tabela-no-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">adicionar novas linhas<\/a> e <a href=\"https:\/\/tableberg.com\/pt\/como-adicionar-uma-coluna-a-uma-tabela-no-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">colunas<\/a> em posi\u00e7\u00f5es espec\u00edficas, usando as respectivas op\u00e7\u00f5es da lista. Voc\u00ea tamb\u00e9m pode <a href=\"https:\/\/tableberg.com\/pt\/como-excluir-uma-linha-de-uma-tabela-no-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">excluir linhas existentes<\/a> e <a href=\"https:\/\/tableberg.com\/pt\/como-excluir-uma-coluna-de-uma-tabela-no-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">colunas<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"654\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Increase-or-delete-the-table-rows-and-columns.png\" alt=\"Aumentar ou excluir as linhas e colunas da tabela\" class=\"has-border-color wp-image-142\" style=\"border-color:#671feb;border-width:1px;border-radius:4px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Increase-or-delete-the-table-rows-and-columns.png 1280w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Increase-or-delete-the-table-rows-and-columns-300x153.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Increase-or-delete-the-table-rows-and-columns-1024x523.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Increase-or-delete-the-table-rows-and-columns-768x392.png 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<p>Outras op\u00e7\u00f5es na barra de ferramentas funcionam de forma semelhante aos outros blocos do Gutenberg.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"3-step-4-add-header-and-footer-to-the-table\">Etapa 4: Adicionar cabe\u00e7alho e rodap\u00e9 \u00e0 tabela<\/h2>\n\n\n\n<p>Venha para o <strong>Op\u00e7\u00e3o de configura\u00e7\u00e3o<\/strong> na barra lateral direita. Voc\u00ea ter\u00e1 op\u00e7\u00f5es para <a href=\"https:\/\/tableberg.com\/pt\/como-adicionar-um-cabecalho-a-uma-tabela-no-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">adicionar o cabe\u00e7alho<\/a> e <a href=\"https:\/\/tableberg.com\/pt\/como-adicionar-um-rodape-a-uma-tabela-no-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">rodap\u00e9<\/a> para a tabela alternando entre as respectivas op\u00e7\u00f5es.<\/p>\n\n\n\n<p>Adicione um cabe\u00e7alho e um rodap\u00e9 \u00e0 tabela se achar necess\u00e1rio.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"654\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-header-and-footer-to-the-table.png\" alt=\"Adicionar cabe\u00e7alho e rodap\u00e9 \u00e0 tabela\" class=\"has-border-color wp-image-143\" style=\"border-color:#671feb;border-width:1px;border-radius:4px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-header-and-footer-to-the-table.png 1280w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-header-and-footer-to-the-table-300x153.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-header-and-footer-to-the-table-1024x523.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Add-header-and-footer-to-the-table-768x392.png 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"4-step-5-stylize-the-table\">Etapa 5: Estilize a mesa<\/h2>\n\n\n\n<p>Venha para o <strong>Estilos<\/strong> na barra lateral direita. Voc\u00ea ter\u00e1 v\u00e1rias op\u00e7\u00f5es, como cor, tipografia, dimens\u00f5es e borda.&nbsp;<\/p>\n\n\n\n<p>Implemente as personaliza\u00e7\u00f5es necess\u00e1rias que voc\u00ea deseja usando essas op\u00e7\u00f5es.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"654\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Stylize-the-table.png\" alt=\"Estilizar a mesa\" class=\"has-border-color wp-image-144\" style=\"border-color:#671feb;border-width:1px;border-radius:4px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Stylize-the-table.png 1280w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Stylize-the-table-300x153.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Stylize-the-table-1024x523.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/Stylize-the-table-768x392.png 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<p>Assim, voc\u00ea pode criar uma tabela adequadamente funcional usando o bloco de tabela padr\u00e3o do Gutenberg no WordPress.<\/p>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_b0e80bf9-bfcb-4239-8505-130be4eac575\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 100%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 2px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"5-conclusion\">Conclus\u00e3o<\/h3>\n\n\n\n<p>Tente sempre manter sua tabela simples e bem estruturada. Escreva o t\u00edtulo de forma clara e adequadamente descritiva para que qualquer pessoa possa entender os dados contidos nas respectivas linhas e colunas. Voc\u00ea pode colocar o texto em negrito, colorido e em it\u00e1lico para que todas as informa\u00e7\u00f5es importantes sejam bem destacadas e as pessoas possam capt\u00e1-las facilmente.<\/p>\n\n\n\n<p>Mas se voc\u00ea quiser criar uma tabela mais atraente com mais op\u00e7\u00f5es, precisar\u00e1 usar um plugin de tabela melhor. Porque o padr\u00e3o n\u00e3o atender\u00e1 \u00e0s suas demandas. <a href=\"https:\/\/wordpress.org\/plugins\/tableberg\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tableberg<\/a> \u00e9 um promissor plug-in de tabela do WordPress que voc\u00ea pode usar nesse caso.<\/p>\n\n\n\n<p>Esse plug-in permitir\u00e1 que voc\u00ea adicione blocos como imagens, bot\u00f5es, listas e muito mais em suas c\u00e9lulas para que voc\u00ea possa exibir informa\u00e7\u00f5es de maneiras mais atraentes.<\/p>","protected":false},"excerpt":{"rendered":"<p>A table is a collection of rows and columns that help organize and display data in a structured format. They allow you to present the most important data clearly and concisely so readers can quickly locate and analyze them without confusion. Furthermore, tables enable you to maintain a consistent and organized layout for presenting information [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[7],"tags":[8],"class_list":["post-138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to","tag-create-a-table"],"featured_image_src":"https:\/\/tableberg.com\/wp-content\/uploads\/2024\/01\/How-to-Create-a-Table-in-WordPress-No-Plugin-Required.png","author_info":{"display_name":"Istiak Rayhan","author_link":"https:\/\/tableberg.com\/pt\/author\/wpx_irayhan\/"},"_links":{"self":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/comments?post=138"}],"version-history":[{"count":7,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts\/138\/revisions"}],"predecessor-version":[{"id":8210,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts\/138\/revisions\/8210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/media\/1664"}],"wp:attachment":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/media?parent=138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/categories?post=138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/tags?post=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}