{"id":8519,"date":"2025-04-25T19:06:17","date_gmt":"2025-04-25T19:06:17","guid":{"rendered":"https:\/\/tableberg.com\/?p=8519"},"modified":"2025-04-26T16:31:03","modified_gmt":"2025-04-26T16:31:03","slug":"como-criar-uma-tabela-de-precos-responsiva-no-wordpress","status":"publish","type":"post","link":"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/","title":{"rendered":"Como criar uma tabela de pre\u00e7os responsiva no WordPress"},"content":{"rendered":"<p>As tabelas sempre foram uma forma fundamental de organizar informa\u00e7\u00f5es. Elas permitem que voc\u00ea apresente v\u00e1rios conjuntos de informa\u00e7\u00f5es em um formato claro e estruturado para que os leitores possam examinar, interpretar e tomar decis\u00f5es rapidamente.<\/p>\n\n\n\n<p>Se voc\u00ea administra uma empresa de SaaS, vende cursos on-line, oferece n\u00edveis de associa\u00e7\u00e3o ou presta servi\u00e7os com diferentes pacotes, acabar\u00e1 precisando de uma tabela de pre\u00e7os. Essa \u00e9 uma das maneiras mais eficientes de apresentar seus planos em um formato lado a lado que mostra o que cada op\u00e7\u00e3o inclui e quanto custa.<\/p>\n\n\n\n<p>Uma tabela de pre\u00e7os responsiva se adapta a diferentes tamanhos de tela. Em um laptop, ela pode mostrar todos os planos em colunas; em um telefone, ela pode empilhar essas colunas em linhas ou permitir que voc\u00ea deslize entre elas. A ideia \u00e9 que o layout permane\u00e7a leg\u00edvel e f\u00e1cil de usar, independentemente do dispositivo utilizado.&nbsp;<\/p>\n\n\n\n<p>\u00c9 por isso que preparamos este artigo com o objetivo de mostrar a voc\u00ea como criar a tabela de pre\u00e7os responsiva perfeita no WordPress. Tenha paci\u00eancia conosco.<\/p>\n\n\n<div data-is_sticky=\"false\" data-sticky_toc_position=\"left\" data-hide_sticky_on_mobile=\"false\" data-sticky_button_icon='&lt;svg style=\"color:#000000;\" class=\"ub_sticky-toc-open-button-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"34px\" width=\"34px\" viewBox=\"0, 0, 448, 512\"&gt;&lt;path fill=\"currentColor\" d=\"M0 96C0 78.33 14.33 64 32 64H416C433.7 64 448 78.33 448 96C448 113.7 433.7 128 416 128H32C14.33 128 0 113.7 0 96zM0 256C0 238.3 14.33 224 32 224H416C433.7 224 448 238.3 448 256C448 273.7 433.7 288 416 288H32C14.33 288 0 273.7 0 256zM416 448H32C14.33 448 0 433.7 0 416C0 398.3 14.33 384 32 384H416C433.7 384 448 398.3 448 416C448 433.7 433.7 448 416 448z\"&gt;&lt;\/svg&gt;' data-sticky_button_color=\"#000000\" data-sticky_toc_width=\"320px\" style=\"max-width: -moz-fit-content; \" class=\"wp-block-ub-table-of-contents-block ub_table-of-contents ub_table-of-contents-collapsed\" id=\"ub_table-of-contents-979822d7-8314-4a23-a0d0-84956bc4435c\" data-linktodivider=\"false\" data-showtext=\"show\" data-hidetext=\"hide\" data-scrolltype=\"auto\" data-enablesmoothscroll=\"false\" data-initiallyhideonmobile=\"false\" data-initiallyshow=\"false\"><div class=\"ub_table-of-contents-header-container\" style=\"background-color: #056161; color: #fff; \">\n\t\t\t<div class=\"ub_table-of-contents-header\" style=\"text-align: left; \">\n\t\t\t\t<div class=\"ub_table-of-contents-title\" style=\"color: #fff; \"><strong>Como criar uma tabela de pre\u00e7os responsiva<\/strong><\/div>\n\t\t\t\t<div class=\"ub_table-of-contents-toggle-icon-container\">\n                    <span class=\"ub_table-of-contents-plus-part ub_horizontal_bar\" style=\"background-color: #fff; \"><\/span>\n                    <span class=\"ub_table-of-contents-plus-part ub_vertical_bar\" style=\"background-color: #fff; \"><\/span>\n                <\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"ub_table-of-contents-extra-container\" style=\"background-color: #fff; \">\n\t\t\t<div class=\"ub_table-of-contents-container ub_table-of-contents-1-column ub-hide\">\n\t\t\t\t<ul style=\"list-style: none; \"><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#0-what-makes-a-pricing-table-perfect-\" style=\"color: #1E1E26; \">O que torna uma tabela de pre\u00e7os perfeita?<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#1-why-skip-the-default-table-block-for-pricing-tables-\" style=\"color: #1E1E26; \">Por que ignorar o bloco de tabela padr\u00e3o para tabelas de pre\u00e7os?<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#2-create-a-responsive-pricing-table-in-wordpress-\" style=\"color: #1E1E26; \">Criar uma tabela de pre\u00e7os responsiva no WordPress<\/a><ul><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#3-step-1-install-and-activate-tableberg-\" style=\"color: #1E1E26; \">Etapa 1: Instalar e ativar o Tableberg<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#4-step-2-add-the-tableberg-block-\" style=\"color: #1E1E26; \">Etapa 2: Adicionar o bloco Tableberg<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#5-step-3-fill-in-the-pricing-details-\" style=\"color: #1E1E26; \">Etapa 3: Preencha os detalhes do pre\u00e7o<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#6-step-4-customize-the-table-styles-\" style=\"color: #1E1E26; \">Etapa 4: Personalizar os estilos de tabela<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#7-step-5-highlight-the-best-value-plan-\" style=\"color: #1E1E26; \">Etapa 5: Destaque o plano de melhor valor<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#8-step-6-fine-tune-your-table-for-responsiveness-\" style=\"color: #1E1E26; \">Etapa 6: Ajuste sua tabela para obter capacidade de resposta<\/a><\/li><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#9-step-7-preview-and-publish-\" style=\"color: #1E1E26; \">Etapa 7: Visualizar e publicar<\/a><ul><li style=\"\"><a href=\"https:\/\/tableberg.com\/pt\/how-to-create-a-responsive-pricing-table-in-wordpress\/#10-final-thoughts-\" style=\"color: #1E1E26; \">Considera\u00e7\u00f5es finais<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-separator-thin\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"0-what-makes-a-pricing-table-perfect-\"><strong>O que torna uma tabela de pre\u00e7os perfeita?<\/strong><\/h2>\n\n\n\n<p>Uma tabela de pre\u00e7os perfeita faz mais do que apenas listar pre\u00e7os. Ela orienta os usu\u00e1rios no processo de tomada de decis\u00e3o com clareza, estrutura e a quantidade certa de \u00eanfase visual. Veja o que ela deve incluir:<\/p>\n\n\n\n<div class=\"wp-block-group is-style-column-box-shadow has-base-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-text-align-center\"><strong>1. Layout claro e focado<\/strong><strong><br><\/strong>Use t\u00edtulos curtos para os planos e mantenha a estrutura f\u00e1cil de examinar. Evite colocar muita coisa. Destaque apenas as principais diferen\u00e7as que realmente importam para seus usu\u00e1rios.<\/p>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-vertical\" id=\"ub_divider_b2e9b73b-630f-461e-94f4-884a9c3d68d4\"><div class=\"ub_divider_wrapper\" style=\"position: relative; width: 2px; height: 20px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-left: 2px dotted #4E4E60; width: fit-content; height: 20px; \"><\/div><div class=\"ub_divider_icon\" data-icon-alignment=\"center\" style=\" \">\n\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"30\" width=\"30\" viewbox=\"0, 0, 320, 512\">\n\t\t<path fill=\"#4E4E60\" d=\"M9.375 329.4c12.51-12.51 32.76-12.49 45.25 0L128 402.8V32c0-17.69 14.31-32 32-32s32 14.31 32 32v370.8l73.38-73.38c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-128 128c-12.5 12.5-32.75 12.5-45.25 0l-128-128C-3.125 362.1-3.125 341.9 9.375 329.4z\">\n\t<\/path><\/svg>\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"has-text-align-center\"><strong>2. Pre\u00e7os honestos e diretos<\/strong><br>Sempre mostre o pre\u00e7o exato e como ele \u00e9 cobrado. Deixe claro se \u00e9 mensal ou anual. Evite frases como \"a partir de\" ou qualquer coisa que oculte o custo real.<\/p>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-vertical\" id=\"ub_divider_67f30652-9901-4499-a50f-e3c5445fdd4b\"><div class=\"ub_divider_wrapper\" style=\"position: relative; width: 2px; height: 20px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-left: 2px dotted #4E4E60; width: fit-content; height: 20px; \"><\/div><div class=\"ub_divider_icon\" data-icon-alignment=\"center\" style=\" \">\n\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"30\" width=\"30\" viewbox=\"0, 0, 320, 512\">\n\t\t<path fill=\"#4E4E60\" d=\"M9.375 329.4c12.51-12.51 32.76-12.49 45.25 0L128 402.8V32c0-17.69 14.31-32 32-32s32 14.31 32 32v370.8l73.38-73.38c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-128 128c-12.5 12.5-32.75 12.5-45.25 0l-128-128C-3.125 362.1-3.125 341.9 9.375 329.4z\">\n\t<\/path><\/svg>\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"has-text-align-center\"><strong>3. Compara\u00e7\u00e3o de recursos lado a lado<\/strong><br>Liste o que est\u00e1 inclu\u00eddo em cada plano e torne as diferen\u00e7as \u00f3bvias. Voc\u00ea pode usar dicas visuais, como \u00edcones ou texto desbotado, para ajudar, mas mantenha a lista limpa e consistente.<\/p>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-vertical\" id=\"ub_divider_3b545e6b-b35c-4d4f-a254-cfd7a03b23e8\"><div class=\"ub_divider_wrapper\" style=\"position: relative; width: 2px; height: 20px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-left: 2px dotted #4E4E60; width: fit-content; height: 20px; \"><\/div><div class=\"ub_divider_icon\" data-icon-alignment=\"center\" style=\" \">\n\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"30\" width=\"30\" viewbox=\"0, 0, 320, 512\">\n\t\t<path fill=\"#4E4E60\" d=\"M9.375 329.4c12.51-12.51 32.76-12.49 45.25 0L128 402.8V32c0-17.69 14.31-32 32-32s32 14.31 32 32v370.8l73.38-73.38c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-128 128c-12.5 12.5-32.75 12.5-45.25 0l-128-128C-3.125 362.1-3.125 341.9 9.375 329.4z\">\n\t<\/path><\/svg>\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"has-text-align-center\"><strong>Slogans de pequenos benef\u00edcios<\/strong><br>Uma linha curta como \"Melhor para freelancers\" ou \"Ideal para equipes\" abaixo de cada plano pode levar seus usu\u00e1rios a tomar uma decis\u00e3o sem pensar demais.&nbsp;<\/p>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-vertical\" id=\"ub_divider_96f98012-133d-4f81-b4fd-ace269c0a202\"><div class=\"ub_divider_wrapper\" style=\"position: relative; width: 2px; height: 20px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-left: 2px dotted #4E4E60; width: fit-content; height: 20px; \"><\/div><div class=\"ub_divider_icon\" data-icon-alignment=\"center\" style=\" \">\n\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"30\" width=\"30\" viewbox=\"0, 0, 320, 512\">\n\t\t<path fill=\"#4E4E60\" d=\"M9.375 329.4c12.51-12.51 32.76-12.49 45.25 0L128 402.8V32c0-17.69 14.31-32 32-32s32 14.31 32 32v370.8l73.38-73.38c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-128 128c-12.5 12.5-32.75 12.5-45.25 0l-128-128C-3.125 362.1-3.125 341.9 9.375 329.4z\">\n\t<\/path><\/svg>\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"has-text-align-center\"><strong>Bot\u00f5es orientados por a\u00e7\u00e3o<br><\/strong>Cada plano deve ter um bot\u00e3o claro que estimule a a\u00e7\u00e3o. Mas n\u00e3o se esque\u00e7a de usar uma cor distinta, um tamanho exclusivo ou um r\u00f3tulo \"Mais popular\" para fazer com que seu plano de melhor valor se destaque.<\/p>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-vertical\" id=\"ub_divider_d3ee934d-d2e0-4ddf-9602-0a7e80865b9c\"><div class=\"ub_divider_wrapper\" style=\"position: relative; width: 2px; height: 20px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-left: 2px dotted #4E4E60; width: fit-content; height: 20px; \"><\/div><div class=\"ub_divider_icon\" data-icon-alignment=\"center\" style=\" \">\n\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"30\" width=\"30\" viewbox=\"0, 0, 320, 512\">\n\t\t<path fill=\"#4E4E60\" d=\"M9.375 329.4c12.51-12.51 32.76-12.49 45.25 0L128 402.8V32c0-17.69 14.31-32 32-32s32 14.31 32 32v370.8l73.38-73.38c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-128 128c-12.5 12.5-32.75 12.5-45.25 0l-128-128C-3.125 362.1-3.125 341.9 9.375 329.4z\">\n\t<\/path><\/svg>\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"has-text-align-center\"><strong>Layout pronto para celular<\/strong><br>Sua tabela deve se adaptar automaticamente a telefones e tablets. O requisito b\u00e1sico \u00e9 manter a legibilidade sem for\u00e7ar os usu\u00e1rios a aplicar zoom ou rolar para os lados.<\/p>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-vertical\" id=\"ub_divider_614a5fd7-e3ed-495c-a554-e2171dfe7898\"><div class=\"ub_divider_wrapper\" style=\"position: relative; width: 2px; height: 20px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-left: 2px dotted #4E4E60; width: fit-content; height: 20px; \"><\/div><div class=\"ub_divider_icon\" data-icon-alignment=\"center\" style=\" \">\n\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"30\" width=\"30\" viewbox=\"0, 0, 320, 512\">\n\t\t<path fill=\"#4E4E60\" d=\"M9.375 329.4c12.51-12.51 32.76-12.49 45.25 0L128 402.8V32c0-17.69 14.31-32 32-32s32 14.31 32 32v370.8l73.38-73.38c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-128 128c-12.5 12.5-32.75 12.5-45.25 0l-128-128C-3.125 362.1-3.125 341.9 9.375 329.4z\">\n\t<\/path><\/svg>\n<\/div>\n<\/div><\/div>\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-19e250f3 wp-block-group-is-layout-constrained\">\n<p class=\"has-text-align-center\"><strong>Add-ons opcionais, mas \u00fateis<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\">Alternativas para alternar entre pre\u00e7os mensais e anuais, dicas de ferramentas r\u00e1pidas ou um link de FAQ pr\u00f3ximo ajudam a responder perguntas comuns antes mesmo que os usu\u00e1rios as fa\u00e7am.<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-full has-custom-border is-style-media-boxed\" style=\"margin-top:var(--wp--preset--spacing--medium);margin-right:0;margin-bottom:var(--wp--preset--spacing--medium);margin-left:0\"><img loading=\"lazy\" decoding=\"async\" width=\"1106\" height=\"646\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Elementor-new.png\" alt=\"\" class=\"has-border-color wp-image-8523\" style=\"border-color:#c2eef6;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Elementor-new.png 1106w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Elementor-new-300x175.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Elementor-new-1024x598.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Elementor-new-768x449.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Elementor-new-18x12.png 18w\" sizes=\"auto, (max-width: 1106px) 100vw, 1106px\" \/><figcaption class=\"wp-element-caption\"><strong>Demonstra\u00e7\u00e3o: Tabela de pre\u00e7os do Elementor<\/strong><\/figcaption><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-separator-thin\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-why-skip-the-default-table-block-for-pricing-tables-\"><strong>Por que ignorar o bloco de tabela padr\u00e3o para tabelas de pre\u00e7os?<\/strong><\/h2>\n\n\n\n<p>Quando voc\u00ea est\u00e1 planejando criar algo no WordPress, sua primeira inten\u00e7\u00e3o pode ser fazer isso com os recursos principais do construtor. Por que desperdi\u00e7ar seu tempo com plugins quando isso pode ser feito com os blocos principais, certo? Em alguns cen\u00e1rios, seus instintos lhe servir\u00e3o bem. Mas quando se trata de criar uma tabela de pre\u00e7os responsiva, o bloco Table padr\u00e3o simplesmente n\u00e3o \u00e9 suficiente.<\/p>\n\n\n\n<p>\u00c9 bom para apresentar dados simples, mas n\u00e3o passa disso. N\u00e3o \u00e9 poss\u00edvel inserir diferentes tipos de conte\u00fado dentro das c\u00e9lulas, n\u00e3o \u00e9 poss\u00edvel estiliz\u00e1-las ou destac\u00e1-las individualmente e n\u00e3o h\u00e1 capacidade de resposta m\u00f3vel integrada. Ele tamb\u00e9m n\u00e3o possui funcionalidade de altern\u00e2ncia e limita o uso de texto simples. Se voc\u00ea tentar us\u00e1-lo para uma tabela de pre\u00e7os, o layout pode parecer bom no desktop, mas rapidamente se desfaz em telas menores. N\u00e3o h\u00e1 empilhamento de colunas, nenhuma maneira de adicionar emblemas ou \u00edcones, nenhum bot\u00e3o de chamada para a\u00e7\u00e3o e nenhuma maneira de enfatizar visualmente um plano em destaque.<\/p>\n\n\n\n<p>Em suma, ele n\u00e3o tem a flexibilidade e a capacidade de resposta que uma tabela de pre\u00e7os adequada precisa. \u00c9 por isso que confiar apenas nos blocos principais nem sempre \u00e9 a op\u00e7\u00e3o mais eficiente.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-separator-thin\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"2-create-a-responsive-pricing-table-in-wordpress-\"><strong>Criar uma tabela de pre\u00e7os responsiva no WordPress<\/strong><\/h2>\n\n\n\n<p>Muitos plug-ins permitem que voc\u00ea crie tabelas de pre\u00e7os, mas geralmente eles v\u00eam com configura\u00e7\u00f5es desnecess\u00e1rias ou usam interfaces complicadas. <a href=\"https:\/\/wordpress.org\/plugins\/tableberg\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tableberg<\/a> \u00e9 diferente. Ele foi criado para o editor de blocos, oferece suporte a v\u00e1rios tipos de conte\u00fado e foi desenvolvido com a capacidade de resposta em mente.  O Tableberg tem um conjunto impressionante de recursos que est\u00e3o prontos para servir de acordo com as necessidades dos usu\u00e1rios.<\/p>\n\n\n<figure class='wp-block-tableberg'>\n                <div class='tableberg-table-wrapper'>\n                    <table\n                        class='wp-block-tableberg'\n                        style='border-collapse: collapse; width: 100%;'\n                        data-tableberg-sortable='false'\n                        data-tableberg-columns='[]'\n                        data-tableberg-pagination='{\"enabled\":false,\"pageSize\":10,\"showPageNumbers\":true,\"showPrevNext\":true}'\n                        data-tableberg-search-enabled='false'\n                        data-tableberg-search-placeholder='Search...'\n                        data-tableberg-search-position='left'\n                        data-tableberg-search-highlight-color=''\n                        data-tableberg-header='true'\n                        data-tableberg-footer='false'\n                        \n            data-tableberg-responsive='true'\n            data-tableberg-rows='9'\n            data-tableberg-cols='2'\n            data-tableberg-tablet-enabled='false'\n            data-tableberg-tablet-width='1024'\n            data-tableberg-tablet-mode='scroll'\n            data-tableberg-tablet-transpose='false'\n            data-tableberg-tablet-count='3'\n            data-tableberg-tablet-repeat-first-col='false'\n            data-tableberg-mobile-enabled='true'\n            data-tableberg-mobile-width='700'\n            data-tableberg-mobile-mode='stack'\n            data-tableberg-mobile-transpose='false'\n            data-tableberg-mobile-count='1'\n            data-tableberg-mobile-repeat-first-col='false'\n        \n                    >\n                        <tbody>\n                            <tr data-tableberg-row='0'><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;background-color:#7d4af7;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='0'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1.38rem'>\n                <strong>Vers\u00e3o gratuita<\/strong>\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;background-color:#7d4af7;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='0'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1.38rem'>\n                <strong>Vers\u00e3o Pro<\/strong>\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><\/tr><tr data-tableberg-row='1'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='1'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Blocos de par\u00e1grafo, lista, bot\u00e3o e imagem\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='1'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Classifica\u00e7\u00e3o por estrelas, \u00edcone, faixa de op\u00e7\u00f5es, blocos HTML personalizados\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='2'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='2'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Design responsivo com empilhamento m\u00f3vel\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='2'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Recurso de altern\u00e2ncia para pre\u00e7os mensais\/anuais\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='3'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='3'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Personaliza\u00e7\u00e3o do cabe\u00e7alho e do rodap\u00e9\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='3'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Linhas e colunas aderentes\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='4'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='4'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Fus\u00e3o de c\u00e9lulas\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='4'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Largura da coluna ajust\u00e1vel\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='5'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='5'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Personaliza\u00e7\u00e3o de cores para cabe\u00e7alho, rodap\u00e9, linhas e colunas.\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='5'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Personaliza\u00e7\u00e3o de cores para c\u00e9lulas, linhas e colunas individuais.\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='6'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='6'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Configura\u00e7\u00e3o e estilo da tabela e da borda interna\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='6'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Configura\u00e7\u00e3o e estilo de bordas de linhas e colunas\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='7'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='7'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Estilo global de fontes e links\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='7'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Funcionalidade de pesquisa e classifica\u00e7\u00e3o\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='8'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='8'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Modelos pr\u00e9-fabricados\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);vertical-align:middle;border-top:1px solid #000000;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;width:50%;min-width:50%'\n                data-cell-row='8'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#000000;font-size:var(--wp--preset--font-size--x-small)'>\n                Disponibilidade de c\u00e9lulas vazias\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr>\n                        <\/tbody>\n                    <\/table>\n                <\/div>\n                \n            <\/figure>\n\n\n<p>Veja como voc\u00ea pode criar uma tabela de pre\u00e7os responsiva usando o Tableberg.<\/p>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_ead15558-2df5-4a50-98f9-5d40cad45900\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 20%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"3-step-1-install-and-activate-tableberg-\"><strong>Etapa 1: Instalar e ativar o Tableberg<\/strong><\/h3>\n\n\n\n<p>V\u00e1 para o painel do WordPress, v\u00e1 para a se\u00e7\u00e3o Plug-in e clique em Adicionar novo. Em seguida, procure o \"Tableberg\", clique para instal\u00e1-lo e, depois, ative-o. Quando estiver ativo, voc\u00ea encontrar\u00e1 o bloco Tableberg dispon\u00edvel no editor de blocos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"415\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Tableberg-install-new-4-1024x415.png\" alt=\"Instala\u00e7\u00e3o e ativa\u00e7\u00e3o do Tableberg\" class=\"has-border-color wp-image-8538\" style=\"border-color:#bceefe;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Tableberg-install-new-4-1024x415.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Tableberg-install-new-4-300x122.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Tableberg-install-new-4-768x312.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Tableberg-install-new-4-18x7.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Tableberg-install-new-4.png 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_676464ab-ef53-4475-a738-22e52be81759\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 20%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"4-step-2-add-the-tableberg-block-\"><strong>Etapa 2: Adicionar o bloco Tableberg <\/strong><\/h3>\n\n\n\n<p>Em seguida, v\u00e1 para qualquer p\u00e1gina existente ou crie uma nova p\u00e1gina na qual voc\u00ea deseja inserir a tabela de pre\u00e7os. Em seu editor, clique no \u00edcone + do inseridor de blocos para adicionar um novo bloco, procure por \"Tableberg\" e insira-o. Escolha o n\u00famero de colunas com base na quantidade de op\u00e7\u00f5es de pre\u00e7os que voc\u00ea deseja mostrar. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"420\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/2-5-1024x420.png\" alt=\" Adicionar o bloco Tableberg\" class=\"has-border-color wp-image-8539\" style=\"border-color:#bceefe;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/2-5-1024x420.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/2-5-300x123.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/2-5-768x315.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/2-5-1536x630.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/2-5-18x7.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/2-5.png 1753w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_0aa206d0-7153-429a-ac17-f9f60feb9c66\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 20%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"5-step-3-fill-in-the-pricing-details-\"><strong>Etapa 3: Preencha os detalhes do pre\u00e7o<\/strong><\/h3>\n\n\n\n<p>Clique dentro de qualquer c\u00e9lula e use o inseridor para adicionar o conte\u00fado necess\u00e1rio. Voc\u00ea pode usar um bloco de par\u00e1grafo para t\u00edtulos de planos, um bloco de lista para recursos, um bloco de bot\u00e3o para chamadas para a\u00e7\u00e3o e \u00edcones ou classifica\u00e7\u00f5es de estrelas sempre que necess\u00e1rio. Basta selecionar a c\u00e9lula, clicar no inseridor de blocos (\u00edcone +) e escolher o bloco que deseja adicionar com base em sua estrutura de pre\u00e7os. Use a configura\u00e7\u00e3o geral do bloco para definir o cabe\u00e7alho e o rodap\u00e9, se necess\u00e1rio. Preencha cada se\u00e7\u00e3o cuidadosamente com base na sua estrutura de pre\u00e7os.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/3-5-1024x461.png\" alt=\"Preencha os detalhes do pre\u00e7o\" class=\"has-border-color wp-image-8542\" style=\"border-color:#bceefe;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/3-5-1024x461.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/3-5-300x135.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/3-5-768x346.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/3-5-1536x692.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/3-5-18x8.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/3-5.png 1747w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_38c3a134-36b7-491d-ad83-fb7a3fa32927\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 20%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"6-step-4-customize-the-table-styles-\"><strong>Etapa 4: Personalizar os estilos de tabela<\/strong><\/h3>\n\n\n\n<p>Clique em qualquer c\u00e9lula, linha ou coluna e, em seguida, abra a barra lateral direita e alterne para a op\u00e7\u00e3o <strong>Estilos<\/strong> tab. A partir da\u00ed, voc\u00ea pode alterar as cores de fundo para destacar se\u00e7\u00f5es, ajustar o preenchimento para adicionar espa\u00e7o dentro das c\u00e9lulas, alinhar o texto corretamente e modificar a largura, a cor e o raio da borda para separar as \u00e1reas de forma limpa.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"866\" height=\"1024\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.1-866x1024.png\" alt=\"Personalizar na guia Styles (Estilos)\" class=\"has-border-color wp-image-8544\" style=\"border-color:#bceefe;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.1-866x1024.png 866w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.1-254x300.png 254w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.1-768x908.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.1-1299x1536.png 1299w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.1-10x12.png 10w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.1.png 1718w\" sizes=\"auto, (max-width: 866px) 100vw, 866px\" \/><\/figure>\n\n\n\n<p>Se quiser agrupar elementos ou separar planos claramente, voc\u00ea pode mesclar c\u00e9lulas. Selecione as c\u00e9lulas que deseja mesclar, clique na borda de uma c\u00e9lula selecionada, abra o menu suspenso da barra de ferramentas de blocos e selecione Edit Table \u2192 Merge (Editar tabela \u2192 Mesclar).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"497\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.2-1024x497.png\" alt=\"Mesclar c\u00e9lulas, se necess\u00e1rio\" class=\"has-border-color wp-image-8545\" style=\"border-color:#bceefe;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.2-1024x497.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.2-300x146.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.2-768x373.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.2-1536x746.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.2-18x9.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/4.2.png 1757w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_f5cf6898-248a-412c-a15e-e2dfeaaf5206\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 20%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"7-step-5-highlight-the-best-value-plan-\"><strong>Etapa 5: Destaque o plano de melhor valor<\/strong><\/h3>\n\n\n\n<p>Clique na coluna que cont\u00e9m sua melhor oferta. Voc\u00ea pode alterar a cor do plano de fundo, adicionar um r\u00f3tulo de fita, como \"Best Value\", e modificar o design do bot\u00e3o para chamar a aten\u00e7\u00e3o instantaneamente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"528\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/5-4-1024x528.png\" alt=\"Adicione cores, fitas e modifique bot\u00f5es. \" class=\"has-border-color wp-image-8546\" style=\"border-color:#bceefe;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/5-4-1024x528.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/5-4-300x155.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/5-4-768x396.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/5-4-1536x793.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/5-4-18x9.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/5-4.png 1645w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"8-step-6-fine-tune-your-table-for-responsiveness-\"><strong>Etapa 6: Ajuste sua tabela para obter capacidade de resposta<\/strong><\/h3>\n\n\n\n<p>Selecione o bloco Tableberg pai e abra o painel de configura\u00e7\u00f5es \u00e0 direita. Role at\u00e9 Responsiveness Settings (Configura\u00e7\u00f5es de capacidade de resposta), escolha Mobile (M\u00f3vel) e ative Enable Breakpoint (Ativar ponto de interrup\u00e7\u00e3o). Defina a Largura m\u00e1xima para definir quando a capacidade de resposta come\u00e7a e ative a op\u00e7\u00e3o Make Top Row Header, se necess\u00e1rio. Em Mode (Modo), escolha Scroll (Rolar) para deslizar horizontalmente ou Stack (Empilhar) para empilhamento vertical. Se estiver usando Stack, ajuste Stack Direction e Items per Row para obter um melhor controle. Visualize sua tabela para verificar a apar\u00eancia dela em diferentes dispositivos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"816\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/6-4-1024x816.png\" alt=\"Aplicar configura\u00e7\u00f5es responsivas\" class=\"has-border-color wp-image-8553\" style=\"border-color:#bceefe;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/6-4-1024x816.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/6-4-300x239.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/6-4-768x612.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/6-4-15x12.png 15w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/6-4.png 1519w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_2d9206a1-61cd-49d9-b8c2-4b6fecd6dd29\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 20%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"9-step-7-preview-and-publish-\"><strong>Etapa 7: Visualizar e publicar<\/strong><\/h3>\n\n\n\n<p>Quando tudo estiver certo, n\u00e3o se esque\u00e7a de visualizar sua tabela nas visualiza\u00e7\u00f5es de desktop, tablet e celular para verificar novamente. Quando estiver pronta, clique em Publish (Publicar) para torn\u00e1-la ativa. Veja um exemplo de como sua tabela de pre\u00e7os poderia ficar seguindo essas etapas:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full has-custom-border is-style-media-boxed\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"584\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/7-2.png\" alt=\"\" class=\"has-border-color wp-image-8556\" style=\"border-color:#bceefe;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/7-2.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/7-2-300x228.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/7-2-16x12.png 16w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_342cd958-3551-4e84-abb7-8390044ab2f7\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 20%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h4 class=\"wp-block-heading\" id=\"10-final-thoughts-\"><strong>Considera\u00e7\u00f5es finais<\/strong><\/h4>\n\n\n\n<p>Examinamos tudo o que voc\u00ea precisa, desde adicionar seus planos e estiliz\u00e1-los adequadamente at\u00e9 configurar a capacidade de resposta da maneira correta. Agora voc\u00ea tem o que \u00e9 preciso para criar uma tabela de pre\u00e7os com boa apar\u00eancia, que funcione em qualquer dispositivo e ajude os usu\u00e1rios a escolher mais rapidamente.<\/p>\n\n\n\n<p>Ao montar sua mesa, tenha em mente algumas coisas. Certifique-se de que seu melhor plano se destaque sem fazer com que a mesa pare\u00e7a lotada. Sempre verifique a apar\u00eancia no celular, n\u00e3o apenas no desktop. E, o mais importante, mantenha-a clara e simples. Se os usu\u00e1rios tiverem que pensar demais, eles ir\u00e3o embora.<\/p>\n\n\n\n<p>Dedique um pouco mais de tempo para preparar as coisas agora e voc\u00ea n\u00e3o ter\u00e1 que consertar nada mais tarde.<\/p>\n\n\n\n<p><strong>Leia tamb\u00e9m:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/tableberg.com\/pt\/melhores-plug-ins-de-tabela-do-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">7 melhores plug-ins de tabela do WordPress em 2024 (comparados)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/tableberg.com\/pt\/como-criar-uma-tabela-responsiva-no-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">Como criar uma tabela responsiva no WordPress<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/tableberg.com\/pt\/melhores-plugins-de-tabela-de-precos-para-wordpress-comparados\/\" target=\"_blank\" rel=\"noreferrer noopener\">7 melhores plug-ins de tabela de pre\u00e7os para WordPress (comparados)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/tableberg.com\/pt\/como-criar-tabelas-empilhaveis-no-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">Como criar tabelas empilh\u00e1veis no WordPress<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Tables have always been a fundamental way to organize information. They let you present multiple sets of information in a clear, structured format so readers can scan, interpret, and make decisions quickly. If you run a SaaS business, sell online courses, offer membership tiers, or provide services with different packages, you\u2019ll eventually fall into the [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":8520,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[7,130],"tags":[],"class_list":["post-8519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to","category-tableberg"],"featured_image_src":"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/04\/Responsive-Tables-850-x-335-px.png","author_info":{"display_name":"Moinul Islam","author_link":"https:\/\/tableberg.com\/pt\/author\/marufmoinul27\/"},"_links":{"self":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts\/8519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/comments?post=8519"}],"version-history":[{"count":28,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts\/8519\/revisions"}],"predecessor-version":[{"id":8607,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts\/8519\/revisions\/8607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/media\/8520"}],"wp:attachment":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/media?parent=8519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/categories?post=8519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/tags?post=8519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}