{"id":8698,"date":"2025-05-02T22:58:12","date_gmt":"2025-05-02T22:58:12","guid":{"rendered":"https:\/\/tableberg.com\/?p=8698"},"modified":"2025-05-04T10:00:53","modified_gmt":"2025-05-04T10:00:53","slug":"como-criar-uma-alternancia-de-precos-mensal-e-anual-no-wordpress","status":"publish","type":"post","link":"https:\/\/tableberg.com\/pt\/how-to-create-a-monthly-yearly-pricing-toggle-in-wordpress\/","title":{"rendered":"Como criar uma altern\u00e2ncia de pre\u00e7os mensais\/anuais no WordPress"},"content":{"rendered":"<p>Os compradores de hoje avaliam as op\u00e7\u00f5es em segundos: alguns examinam os pre\u00e7os, outros comparam os recursos e muitos debatem sobre planos mensais ou anuais. Nesse ambiente de tomada de decis\u00e3o em fra\u00e7\u00f5es de segundo, o design de sua tabela de pre\u00e7os se torna o fator decisivo nas convers\u00f5es.<\/p>\n\n\n\n<p>Se voc\u00ea administra um servi\u00e7o ou um neg\u00f3cio baseado em assinatura, sua tabela de pre\u00e7os precisa fazer mais do que listar op\u00e7\u00f5es para converter visitantes em clientes pagantes. Ela deve orientar a aten\u00e7\u00e3o, apoiar compara\u00e7\u00f5es e fazer com que o melhor plano pare\u00e7a ser a escolha \u00f3bvia.<\/p>\n\n\n\n<p>Uma tabela de pre\u00e7os bem projetada com uma altern\u00e2ncia mensal\/anual transforma uma tabela de pre\u00e7os padr\u00e3o em algo muito mais din\u00e2mico e focado no usu\u00e1rio. Ela n\u00e3o apenas exibe op\u00e7\u00f5es, mas orienta ativamente o olhar, enfatiza a economia e elimina o atrito da compara\u00e7\u00e3o.<\/p>\n\n\n\n<p>Neste guia, voc\u00ea aprender\u00e1 a criar uma altern\u00e2ncia limpa de pre\u00e7os mensais e anuais no WordPress usando um formato de tabela que fica \u00f3timo em qualquer dispositivo.<\/p>\n\n\n\n<div class=\"wp-block-cover aligncenter has-custom-content-position is-position-top-center is-style-default\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-container-core-cover-is-layout-f5f3bcb8 wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\">Altern\u00e2ncia de pre\u00e7os mensais\/anuais<\/p>\n\n\n\n<div class=\"wp-block-tableberg-pro-toggle\"><figure class='wp-block-tableberg'>\n                <div class='tableberg-table-wrapper'>\n                    <table\n                        class='wp-block-tableberg tableberg-has-cell-spacing tableberg-cell-spacing-vertical-zero'\n                        style='border-collapse: separate; border-spacing: 2px 0; width: 100%;'\n                        data-tableberg-sortable='false'\n                        data-tableberg-columns='[]'\n                        data-tableberg-pagination='{\"enabled\":false,\"pageSize\":10,\"showPageNumbers\":true,\"showPrevNext\":true}'\n                        data-tableberg-search-enabled='false'\n                        data-tableberg-search-placeholder='Search...'\n                        data-tableberg-search-position='left'\n                        data-tableberg-search-highlight-color=''\n                        data-tableberg-header='true'\n                        data-tableberg-footer='false'\n                        \n                    >\n                        <tbody>\n                            <tr data-tableberg-row='0'><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#2692b9;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='0'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1.38rem'>\n                B\u00e1sico\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#5b0fbf;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='0'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1rem'>\n                Profissional\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#2692b9;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='0'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1.38rem'>\n                Empresa\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><\/tr><tr data-tableberg-row='1'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                Para pessoas f\u00edsicas\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                Para startups\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                Para grandes empresas\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='2'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $99\/m\u00eas\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $199\/m\u00eas\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $299\/m\u00eas\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='3'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='3'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                Todos os recursos de an\u00e1lise\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                At\u00e9 250.000 visitas rastreadas\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                Suporte normal\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                At\u00e9 3 membros da equipe\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='3'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                Todos os recursos de an\u00e1lise\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                At\u00e9 1.000.000 de visitas rastreadas\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                Suporte Premium\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                At\u00e9 10 membros da equipe\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='3'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                Todos os recursos de an\u00e1lise\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                At\u00e9 5.000.000 de visitas rastreadas\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                Suporte dedicado\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                At\u00e9 50 membros da equipe\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='4'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    Comece a usar\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    Comece a usar\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:var(--wp--preset--spacing--0)'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    Comece a usar\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr>\n                        <\/tbody>\n                    <\/table>\n                <\/div>\n                \n            <\/figure>\n\n<figure class='wp-block-tableberg'>\n                <div class='tableberg-table-wrapper'>\n                    <table\n                        class='wp-block-tableberg tableberg-has-cell-spacing tableberg-cell-spacing-vertical-zero'\n                        style='border-collapse: separate; border-spacing: 2px 0; width: 100%;'\n                        data-tableberg-sortable='false'\n                        data-tableberg-columns='[]'\n                        data-tableberg-pagination='{\"enabled\":false,\"pageSize\":10,\"showPageNumbers\":true,\"showPrevNext\":true}'\n                        data-tableberg-search-enabled='false'\n                        data-tableberg-search-placeholder='Search...'\n                        data-tableberg-search-position='left'\n                        data-tableberg-search-highlight-color=''\n                        data-tableberg-header='true'\n                        data-tableberg-footer='false'\n                        \n                    >\n                        <tbody>\n                            <tr data-tableberg-row='0'><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#2692b9;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:60px;min-height:60px'\n                data-cell-row='0'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1.38rem'>\n                B\u00e1sico\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#5b0fbf;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:60px;min-height:60px'\n                data-cell-row='0'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1rem'>\n                Profissional\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><th\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;background-color:#2692b9;border-top:1px solid #000000;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:60px;min-height:60px'\n                data-cell-row='0'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:var(--wp--preset--color--base);--tableberg-text-link-color:var(--wp--preset--color--base);font-size:1.38rem'>\n                Empresa\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/th><\/tr><tr data-tableberg-row='1'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                Para pessoas f\u00edsicas\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                Para startups\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='1'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                Para grandes empresas\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='2'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $990\/ano\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $1990\/ano\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='2'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:center;width:100%'\n                >\n                    <p class='tableberg-text-element' style='margin:0;color:#fff;font-size:1.38rem'>\n                $2990\/ano\n            <\/p>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='3'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:0px;min-height:0px'\n                data-cell-row='3'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                Todos os recursos de an\u00e1lise\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                At\u00e9 250.000 visitas rastreadas\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                Suporte normal\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                At\u00e9 3 membros da equipe\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:0px;min-height:0px'\n                data-cell-row='3'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                Todos os recursos de an\u00e1lise\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                At\u00e9 1.000.000 de visitas rastreadas\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                Suporte Premium\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 var(--wp--preset--spacing--0) 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:1.38rem;color:#000000;flex:1'>\n                At\u00e9 10 membros da equipe\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;height:0px;min-height:0px'\n                data-cell-row='3'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div class='tableberg-list'>\n                    <ul style='list-style-type:none;margin:0;padding-left:0'>\n                        <li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                Todos os recursos de an\u00e1lise\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                At\u00e9 5.000.000 de visitas rastreadas\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                Suporte dedicado\n            <\/span>\n                    <\/div>\n                    \n                <\/li><li>\n                    <div style='display:flex;padding:4px 0;gap:var(--wp--preset--spacing--20);margin:0 0 0 0'>\n                        <span style='display:flex;align-items:center;justify-content:center;color:#fff;font-size:12px;min-width:12px'>\n                            <svg\n                width='12'\n                height='12'\n                viewbox='0 0 512 512'\n                fill='currentColor'\n            >\n                <path d='M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z' \/>\n            <\/svg>\n                        <\/span>\n                        <span style='font-size:var(--wp--preset--font-size--.95rem);color:#000000;flex:1'>\n                At\u00e9 50 membros da equipe\n            <\/span>\n                    <\/div>\n                    \n                <\/li>\n                    <\/ul>\n                <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr><tr data-tableberg-row='4'><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='0'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    Comece a usar\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='1'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    Comece a usar\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><td\n                rowspan='1'\n                colspan='1'\n                \n                style='position:relative;padding-top:0;padding-right:var(--wp--preset--spacing--small);padding-bottom:0;padding-left:var(--wp--preset--spacing--small);vertical-align:middle;border-right:1px solid #000000;border-bottom:1px solid #000000;border-left:1px solid #000000;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px'\n                data-cell-row='4'\n                data-cell-col='2'\n                \n            >\n                <div\n                class='tableberg-cell-elements'\n                style='display:flex;flex-direction:column;justify-content:center;align-items:stretch;flex-wrap:nowrap;gap:0'\n            >\n                <div\n                    class='tableberg-cell-element'\n                    style='display:flex;justify-content:flex-start;width:100%'\n                >\n                    <div id='' style='display:flex;justify-content:flex-start;--tableberg-button-background-color:#000000;--tableberg-button-text-color:#ffffff;--tableberg-button-hover-background-color:#000000;--tableberg-button-text-hover-color:#ffffff'>\n                <div\n                    class='wp-block-button__link wp-element-button'\n                    style='display:inline-block;text-align:center;font-size:0.75rem;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px'\n                >\n                    Comece a usar\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div>\n                \n                \n            <\/td><\/tr>\n                        <\/tbody>\n                    <\/table>\n                <\/div>\n                \n            <\/figure><\/div>\n\n\n\n<p class=\"has-text-align-right has-text-color has-link-color has-x-small-font-size wp-elements-e6213d2371abd0098c7eb5ddc3b9b893\" style=\"border-style:none;border-width:0px;color:#55a3bd;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\"><a href=\"https:\/\/wordpress.org\/plugins\/tableberg\/\" target=\"_blank\" rel=\"noreferrer noopener\">Constru\u00eddo com Tableberg<\/a><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como adicionar uma altern\u00e2ncia de pre\u00e7o mensal\/anual no WordPress<\/strong><\/h2>\n\n\n\n<p>Agora que voc\u00ea j\u00e1 sabe como uma altern\u00e2ncia de pre\u00e7os ajuda a simplificar as compara\u00e7\u00f5es e a destacar o valor, vamos percorrer as etapas para criar uma usando o plug-in Tableberg.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa 1: Instalar e ativar o Tableberg<\/strong><\/h3>\n\n\n\n<p>V\u00e1 at\u00e9 o painel do WordPress, acesse Plugins \u2192 Adicionar novo, procure por Tableberg e clique em Instalar agora, seguido de Ativar. Depois de ativado, voc\u00ea encontrar\u00e1 dois novos blocos no editor: Tableberg e Toggle for Tableberg.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"415\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new-1024x415.png\" alt=\"\" class=\"has-border-color wp-image-8629\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new-1024x415.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new-300x122.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new-768x312.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new-18x7.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/Tableberg-install-new.png 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_9f5958f1-8c4c-4765-95e3-a9826d69c747\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa 2: Adicionar a altern\u00e2ncia para o bloco Tableberg<\/strong><\/h3>\n\n\n\n<p>Abra o post ou a p\u00e1gina onde deseja colocar sua tabela de pre\u00e7os. Clique no \u00edcone de adi\u00e7\u00e3o, pesquise Toggle for Tableberg e insira o bloco. Ele come\u00e7a com tr\u00eas guias por padr\u00e3o. Passe o mouse sobre qualquer guia para remov\u00ea-la ou clique no sinal de mais para adicionar mais. Para essa configura\u00e7\u00e3o, mantenha apenas duas guias - uma para \"Monthly\" (Mensal) e outra para \"Yearly\" (Anual).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"454\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-1024x454.png\" alt=\"\" class=\"has-border-color wp-image-8724\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-1024x454.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-300x133.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-768x340.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-1536x681.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2-18x8.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/2-2.png 1791w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_ba951f5b-ed3e-42ee-ac13-c66dff4e4fd2\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa 3: Configurar as defini\u00e7\u00f5es da guia<\/strong><\/h3>\n\n\n\n<p>Com o bloco selecionado, use o painel de configura\u00e7\u00f5es \u00e0 direita para ajustar as op\u00e7\u00f5es General e Style.<\/p>\n\n\n\n<p>Na guia General (Geral), renomeie cada guia, escolha qual delas estar\u00e1 ativa por padr\u00e3o e alinhe as guias conforme necess\u00e1rio. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-1024x509.png\" alt=\"\" class=\"has-border-color wp-image-8725\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-1024x509.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-300x149.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-768x381.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-1536x763.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1-18x9.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.1-1.png 1760w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Em Style (Estilo), voc\u00ea pode ajustar as cores das guias ativas e inativas, definir o espa\u00e7amento abaixo da altern\u00e2ncia e ajustar o raio da borda para arredondar os cantos, se quiser um visual mais suave.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"564\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-1024x564.png\" alt=\"\" class=\"has-border-color wp-image-8726\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-1024x564.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-300x165.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-768x423.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-1536x846.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1-18x10.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/3.2-1.png 1744w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_3c8aeef2-8a17-427b-b2ca-bc3d2521baa2\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa 4: Adicionar tabelas dentro de cada guia<\/strong><\/h3>\n\n\n\n<p>Clique na primeira guia e crie a tabela. Ela conter\u00e1 sua tabela de pre\u00e7os mensal. Repita o mesmo procedimento na segunda guia e adicione sua vers\u00e3o anual. Sua estrutura para ambas as tabelas deve permanecer a mesma, alterando apenas os pre\u00e7os e os r\u00f3tulos relacionados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"500\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-1024x500.png\" alt=\"\" class=\"has-border-color wp-image-8727\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-1024x500.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-300x147.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-768x375.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-1536x750.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2-18x9.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/4-2.png 1681w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_ddfc08f8-af64-49b2-ae15-3f4d799fef78\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa 5: Personalizar as tabelas<\/strong><\/h3>\n\n\n\n<p>Adicione nomes de planos, tags de p\u00fablico-alvo, pre\u00e7os, recursos e bot\u00f5es de chamada para a\u00e7\u00e3o dentro de cada coluna. Use blocos de par\u00e1grafos, listas e blocos de bot\u00f5es dentro das c\u00e9lulas da tabela.&nbsp;<\/p>\n\n\n\n<p>Em seguida, abra as configura\u00e7\u00f5es gerais para definir o cabe\u00e7alho e o rodap\u00e9 e ajuste recursos como cabe\u00e7alho fixo, classifica\u00e7\u00e3o e pesquisa, se necess\u00e1rio. Por fim, use a guia estilo para ajustar o espa\u00e7amento, as cores de fundo, as bordas e o alinhamento para obter uma apar\u00eancia limpa e consistente em ambas as tabelas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"489\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-1024x489.png\" alt=\"\" class=\"has-border-color wp-image-8728\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-1024x489.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-300x143.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-768x367.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-1536x733.png 1536w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2-18x9.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/5-2.png 1825w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_8a54aa64-d7a8-4877-be81-4356468a3997\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>Etapa 6: Salvar, visualizar e publicar<\/strong><\/h3>\n\n\n\n<p>N\u00e3o se esque\u00e7a de salvar seu trabalho primeiro. Em seguida, use a op\u00e7\u00e3o de visualiza\u00e7\u00e3o para verificar a apar\u00eancia da altern\u00e2ncia no desktop e no celular. Certifique-se de que a altern\u00e2ncia de guias seja suave e que cada vers\u00e3o da tabela seja clara. Quando estiver satisfeito, clique em Publish (Publicar) para torn\u00e1-lo ativo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"548\" src=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1-1024x548.png\" alt=\"\" class=\"has-border-color wp-image-8729\" style=\"border-color:#bfe9fa;border-width:1px;border-radius:2px\" srcset=\"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1-1024x548.png 1024w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1-300x161.png 300w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1-768x411.png 768w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1-18x10.png 18w, https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/6-1.png 1473w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-ub-divider ub_divider ub-divider-orientation-horizontal\" id=\"ub_divider_cd938526-ab9a-4931-afaf-11427927d265\"><div class=\"ub_divider_wrapper\" style=\"position: relative; margin-bottom: 2px; width: 30%; height: 2px; \" data-divider-alignment=\"center\"><div class=\"ub_divider_line\" style=\"border-top: 3px solid #ccc; margin-top: 2px; \"><\/div><\/div><\/div>\n\n\n<p><strong>Considera\u00e7\u00f5es finais<\/strong><\/p>\n\n\n\n<p>Uma altern\u00e2ncia de pre\u00e7os mensal\/anual n\u00e3o \u00e9 apenas um truque de design. \u00c9 uma maneira pr\u00e1tica de apresentar op\u00e7\u00f5es de faturamento flex\u00edveis sem sobrecarregar seu layout. Com o Tableberg, voc\u00ea n\u00e3o precisa de plugins extras ou c\u00f3digo personalizado para fazer isso direito. Voc\u00ea pode criar uma tabela de pre\u00e7os responsiva e bem estruturada que ajuda os visitantes a comparar os planos com clareza e escolher o que melhor se adapta a eles.<\/p>\n\n\n\n<p>Reserve um tempo para configurar a altern\u00e2ncia com cuidado e voc\u00ea ter\u00e1 uma p\u00e1gina mais limpa e uma experi\u00eancia de tomada de decis\u00e3o mais tranquila para seus usu\u00e1rios.<\/p>","protected":false},"excerpt":{"rendered":"<p>Today&#8217;s buyers evaluate options in seconds: some scan prices, others compare features, and many debate monthly versus annual plans. In this split-second decision-making environment, your pricing table&#8217;s design becomes the decisive factor in conversions. If you run a service or subscription-based business, your pricing table needs to do more than list options to convert visitors [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":8700,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[7,130],"tags":[],"class_list":["post-8698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to","category-tableberg"],"featured_image_src":"https:\/\/tableberg.com\/wp-content\/uploads\/2025\/05\/MonthlyYearly-Pricing-Toggle-850-x-335-px.png","author_info":{"display_name":"Moinul Islam","author_link":"https:\/\/tableberg.com\/pt\/author\/marufmoinul27\/"},"_links":{"self":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts\/8698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/comments?post=8698"}],"version-history":[{"count":39,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts\/8698\/revisions"}],"predecessor-version":[{"id":8761,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/posts\/8698\/revisions\/8761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/media\/8700"}],"wp:attachment":[{"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/media?parent=8698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/categories?post=8698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tableberg.com\/pt\/wp-json\/wp\/v2\/tags?post=8698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}